{"id":2728,"date":"2013-06-06T18:45:05","date_gmt":"2013-06-06T17:45:05","guid":{"rendered":"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/06\/veille05.jpg"},"modified":"2013-06-06T18:45:05","modified_gmt":"2013-06-06T17:45:05","slug":"veille05","status":"inherit","type":"attachment","link":"https:\/\/www.team-outdoor.fr\/blog\/veille05\/","title":{"rendered":"veille05"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":{"ngg_post_thumbnail":0},"class_list":["post-2728","attachment","type-attachment","status-inherit","hentry","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"description":{"rendered":"<p><a href='https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/06\/veille05.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/06\/veille05-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/06\/veille05-1024x683.jpg 1024w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/06\/veille05-300x200.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/06\/veille05-600x400.jpg 600w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/06\/veille05.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2000,"height":1334,"file":"2013\/06\/veille05.jpg","sizes":{"thumbnail":{"file":"veille05-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/06\/veille05-150x150.jpg"},"medium":{"file":"veille05-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/06\/veille05-300x200.jpg"},"large":{"file":"veille05-1024x683.jpg","width":1024,"height":683,"mime_type":"image\/jpeg","source_url":"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/06\/veille05-1024x683.jpg"},"wysija-newsletters-max":{"file":"veille05-600x400.jpg","width":600,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/06\/veille05-600x400.jpg"},"full":{"file":"veille05.jpg","width":2000,"height":1334,"mime_type":"image\/jpeg","source_url":"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/06\/veille05.jpg"}},"image_meta":{"aperture":4,"credit":"","camera":"Canon EOS 450D","caption":"","created_timestamp":1369942562,"copyright":"","focal_length":"17","iso":"400","shutter_speed":"0.033333333333333","title":""}},"post":null,"source_url":"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/06\/veille05.jpg","_links":{"self":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/media\/2728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/comments?post=2728"}]}}