{"id":2851,"date":"2013-07-09T12:31:33","date_gmt":"2013-07-09T11:31:33","guid":{"rendered":"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/07\/veille130613-30.jpg"},"modified":"2013-07-09T12:31:33","modified_gmt":"2013-07-09T11:31:33","slug":"veille130613-30","status":"inherit","type":"attachment","link":"https:\/\/www.team-outdoor.fr\/blog\/veille130613-30\/","title":{"rendered":"veille130613-30"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":{"ngg_post_thumbnail":0},"class_list":["post-2851","attachment","type-attachment","status-inherit","hentry","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"description":{"rendered":"<p><a href='https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/07\/veille130613-30.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/07\/veille130613-30-1024x682.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/07\/veille130613-30-1024x682.jpg 1024w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/07\/veille130613-30-300x199.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/07\/veille130613-30-600x399.jpg 600w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/07\/veille130613-30.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2000,"height":1333,"file":"2013\/07\/veille130613-30.jpg","sizes":{"thumbnail":{"file":"veille130613-30-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/07\/veille130613-30-150x150.jpg"},"medium":{"file":"veille130613-30-300x199.jpg","width":300,"height":199,"mime_type":"image\/jpeg","source_url":"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/07\/veille130613-30-300x199.jpg"},"large":{"file":"veille130613-30-1024x682.jpg","width":1024,"height":682,"mime_type":"image\/jpeg","source_url":"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/07\/veille130613-30-1024x682.jpg"},"wysija-newsletters-max":{"file":"veille130613-30-600x399.jpg","width":600,"height":399,"mime_type":"image\/jpeg","source_url":"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/07\/veille130613-30-600x399.jpg"},"full":{"file":"veille130613-30.jpg","width":2000,"height":1333,"mime_type":"image\/jpeg","source_url":"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/07\/veille130613-30.jpg"}},"image_meta":{"aperture":6.29999999999999982236431605997495353221893310546875,"credit":"","camera":"Canon EOS 450D","caption":"","created_timestamp":1371154053,"copyright":"","focal_length":"17","iso":"400","shutter_speed":"0.0125","title":""}},"post":null,"source_url":"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/07\/veille130613-30.jpg","_links":{"self":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/media\/2851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/comments?post=2851"}]}}