{"id":620,"date":"2013-02-27T10:39:21","date_gmt":"2013-02-27T09:39:21","guid":{"rendered":"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/02\/P1150759.jpg"},"modified":"2013-02-27T10:39:21","modified_gmt":"2013-02-27T09:39:21","slug":"p1150759","status":"inherit","type":"attachment","link":"https:\/\/www.team-outdoor.fr\/blog\/p1150759\/","title":{"rendered":"P1150759"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":{"ngg_post_thumbnail":0},"class_list":["post-620","attachment","type-attachment","status-inherit","hentry","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"description":{"rendered":"<p><a href='https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/02\/P1150759.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/02\/P1150759.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/02\/P1150759.jpg 800w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/02\/P1150759-300x225.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/02\/P1150759-600x450.jpg 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>bandes noires et jaunes<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":800,"height":600,"file":"2013\/02\/P1150759.jpg","sizes":{"thumbnail":{"file":"P1150759-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/02\/P1150759-150x150.jpg"},"medium":{"file":"P1150759-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/02\/P1150759-300x225.jpg"},"wysija-newsletters-max":{"file":"P1150759-600x450.jpg","width":600,"height":450,"mime_type":"image\/jpeg","source_url":"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/02\/P1150759-600x450.jpg"},"full":{"file":"P1150759.jpg","width":800,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/02\/P1150759.jpg"}},"image_meta":{"aperture":3.20000000000000017763568394002504646778106689453125,"credit":"Picasa","camera":"DMC-FZ50","caption":"","created_timestamp":1361959860,"copyright":"","focal_length":"16.6","iso":"100","shutter_speed":"0.016666666666667","title":""}},"post":null,"source_url":"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/02\/P1150759.jpg","_links":{"self":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/media\/620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/comments?post=620"}]}}