{"id":1120,"date":"2013-04-11T12:02:42","date_gmt":"2013-04-11T11:02:42","guid":{"rendered":"http:\/\/www.team-outdoor.fr\/blog\/?p=1120"},"modified":"2013-05-17T19:56:05","modified_gmt":"2013-05-17T18:56:05","slug":"lecotrail-de-paris-quelques-conseils","status":"publish","type":"post","link":"https:\/\/www.team-outdoor.fr\/blog\/lecotrail-de-paris-quelques-conseils\/","title":{"rendered":"L&rsquo;\u00e9cotrail de Paris, quelques conseils"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><span style=\"color: #000000; font-size: 22px;\">pour la derni\u00e8re ligne droite&#8230;<\/span><\/strong><\/p>\n<p><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/ecotrail-paris.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"250\" class=\"wp-image-1123 alignnone\" style=\"margin: 5px;\" alt=\"ecotrail paris\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/ecotrail-paris.jpg\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/ecotrail-paris.jpg 700w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/ecotrail-paris-300x107.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p><span style=\"font-size: 14px;\"><strong><span style=\"color: #000000;\">Bonjour \u00e0 tous!<br class=\"none\" \/><\/span><\/strong><\/span><br \/>\n<span style=\"font-size: 14px;\"><span style=\"color: #000000;\"> A la capitale c&rsquo;est J-1 ou J-2 avant l&rsquo;\u00e9cotrail 2013 pour ses 5 \u00e9preuves : le 80 kils, le 50 kils et le 30 kils qui ont lieu demain et la Twin Sant\u00e9 et l&rsquo;\u00e9preuve de marche nordique qui se d\u00e9rouleront dimanche.<\/span> <span style=\"color: #000000;\">Quelques trucs et astuces pour les coureurs qui prendront le d\u00e9part demain direction le champs de Mars. Ce ne sont que des menus conseils, chacun y verra ce qui lui convient&#8230;<\/span><\/span><\/p>\n<p><span style=\"color: #000000; font-size: 14px;\"><strong> <a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/d\u00e9shydratation.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"245\" class=\" wp-image-1122 alignright\" style=\"margin: 5px;\" alt=\"d\u00e9shydratation\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/d\u00e9shydratation-300x245.jpg\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/d\u00e9shydratation-300x245.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/d\u00e9shydratation.jpg 320w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>1. M\u00eame s&rsquo;il s&rsquo;agit d&rsquo;un trail qui a la r\u00e9putation d&rsquo;\u00eatre roulant,<\/strong> avec ses dix derniers kilom\u00e8tres le long des quais, nous conseillons aux coureurs de partir avec leurs chaussures de trail, au vu des conditions de ces derniers jours<\/span><\/p>\n<p><span style=\"color: #000000; font-size: 14px;\"><strong> 2. Samedi cot\u00e9 m\u00e9t\u00e9o c&rsquo;est annonc\u00e9 nuageux sans trop de pluie<\/strong> avec des temp\u00e9ratures comprises entre 6 et 11 \u00b0C : ce sont les temp\u00e9ratures id\u00e9ales, ni trop chaud, ni trop froid. Attention cependant \u00e0 bien penser \u00e0 vous hydrater, car quand il fait frais, on n&rsquo;y pense beaucoup moins. La d\u00e9shydratation est vite arriv\u00e9e et sans que l&rsquo;on s&rsquo;en rendre compte.<\/span><\/p>\n<p><span style=\"color: #000000; font-size: 14px;\"><strong> 3. Cot\u00e9 nourriture, alternez sucr\u00e9 et sal\u00e9<\/strong> afin de ne pas voir apparaitre le d\u00e9gout du sucr\u00e9. Rien de tels que des petits morceaux de fromage coup\u00e9s en d\u00e9s mis dans un sachet cong\u00e9lo dans lequel on pioche de temps \u00e0 autre ;)<\/span><\/p>\n<p><span style=\"color: #000000; font-size: 14px;\"><strong> <a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/li\u00e8vre-et-tortue.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"171\" class=\" wp-image-1124 alignleft\" style=\"margin: 5px;\" alt=\"li\u00e8vre et tortue\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/li\u00e8vre-et-tortue-300x171.jpg\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/li\u00e8vre-et-tortue-300x171.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/li\u00e8vre-et-tortue.jpg 424w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>4. Attention : les d\u00e9parts du 50 kils et du 80 kils (surtout ce dernier d&rsquo;ailleurs) sont tr\u00e8s roulants.<\/strong> il est tr\u00e8s facile de se laisser emporter par l&rsquo;euphorie g\u00e9n\u00e9rale et de se mettre en sur-r\u00e9gime. Mettez le frein \u00e0 mains! Vous pourrez profiter des 10 derniers kilom\u00e8tres allant de Saint Cloud au Champs de Mars pour l\u00e2cher les chevaux!<\/span><\/p>\n<p><span style=\"color: #000000; font-size: 14px;\"><strong> 5. Pour la plupart des coureurs, il peut \u00eatre opportun d&rsquo;adopter la tactique de \u00ab\u00a0je marche dans toutes les c\u00f4tes et ce, d\u00e8s le d\u00e9but\u00a0\u00bb!<\/strong> Vous ne perdez pas tellement en vitesse d&rsquo;\u00e9volution entre la marche et la course en c\u00f4te : tout au plus 0.5 kil\/h \u00e0 1 kil\/h. Par contre, votre coeur a vite fait de s&#8217;emballer en prenant 10 \u00e0 20 puls suppl\u00e9mentaire par rapport au plat. Arriv\u00e9 en haut de la cote, il est alors compliqu\u00e9 de repartir de suite sur votre vitesse de croisi\u00e8re. Alors que si<\/span><span style=\"color: #000000; font-size: 14px;\"><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/Arriv\u00e9e-ecotrail.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" class=\" wp-image-1134 alignright\" style=\"margin: 5px;\" alt=\"Arriv\u00e9e ecotrail\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/Arriv\u00e9e-ecotrail-300x200.jpg\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/Arriv\u00e9e-ecotrail-300x200.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/Arriv\u00e9e-ecotrail.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/span><span style=\"color: #000000; font-size: 14px;\"> votre coeur n&rsquo;est pas trop haut, suite \u00e0 une c\u00f4te march\u00e9e, vous repartez \u00e0 votre rythme directement&#8230;. et au fil du chemin, vous gagnerez du temps et du plaisir! Perso, c&rsquo;est l<\/span><span style=\"color: #000000; font-size: 14px;\">a tactique que j&rsquo;avais adopt\u00e9e il y a deux ans. Certes au d\u00e9part, on se fait un peut chambrer par ceux qui nous doublent en courant dans les cotes et que l&rsquo;on repasse \u00e7 chaque f<\/span><span style=\"color: #000000; font-size: 14px;\">ois sur le plat, mais \u00e0 partir d&rsquo;un moment, tout le monde marche en cote&#8230; mai vous, vous \u00eates plus frais et sur le plat vous allez plus vite avec un maximum de plaisir!<\/span><\/p>\n<p><span style=\"color: #000000; font-size: 14px;\"><strong> Sur ce, nous vous souhaitons une tr\u00e8s belle course,<\/strong> beaucoup de plaisir. Donnez-nous, ici votre dossard, si vous voulez qu&rsquo;on vous suive ;)<\/span> <span style=\"color: #000000; font-size: 14px;\">Nous souhaitons une bonne course \u00e9galement \u00e0 alexandre (50 kils) qui a le plaisir de vous accueillir au magasin tous les jours ainsi qu&rsquo;\u00e0 Tonio (<strong>Antoine ALLONGUE<\/strong>) et Ben (<strong>Benoit GANDELOT<\/strong>) qui repr\u00e9senteront le TOP (Team Outdoor Paris) sur le 50 kils \u00e9galement!<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>pour la derni\u00e8re ligne droite&#8230; Bonjour \u00e0 tous! A la capitale c&rsquo;est J-1 ou J-2 avant l&rsquo;\u00e9cotrail 2013 pour ses 5 \u00e9preuves : le 80 kils, le 50 kils et le 30 kils qui ont lieu demain et la Twin Sant\u00e9 et l&rsquo;\u00e9preuve de marche nordique qui se d\u00e9rouleront dimanche. Quelques trucs et astuces pour [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1129,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[55],"tags":[],"class_list":["post-1120","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coin-conseils","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"_links":{"self":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts\/1120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/comments?post=1120"}],"version-history":[{"count":10,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts\/1120\/revisions"}],"predecessor-version":[{"id":1128,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts\/1120\/revisions\/1128"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/media\/1129"}],"wp:attachment":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/media?parent=1120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/categories?post=1120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/tags?post=1120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}