{"id":12166,"date":"2017-01-18T12:43:53","date_gmt":"2017-01-18T11:43:53","guid":{"rendered":"http:\/\/www.team-outdoor.fr\/blog\/?p=12166"},"modified":"2017-01-18T17:11:05","modified_gmt":"2017-01-18T16:11:05","slug":"nicolas-duhail-portrait-et-en-route-vers-2017","status":"publish","type":"post","link":"https:\/\/www.team-outdoor.fr\/blog\/nicolas-duhail-portrait-et-en-route-vers-2017\/","title":{"rendered":"Nicolas DUHAIL, portrait et en route vers 2017"},"content":{"rendered":"<p style=\"text-align: justify;\"><br class=\"none\"><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/30986735.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-12167\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/30986735-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/30986735-1024x683.jpg 1024w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/30986735-300x200.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/30986735-768x512.jpg 768w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/30986735-600x400.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><br class=\"none\"><br class=\"none\"><span style=\"font-size: 12pt; color: #000000;\">Une ann\u00e9e qui commence est traditionnellement l\u2019occasion de faire le point sur celle qui se termine et de se donner des objectifs. cela permet \u00e9galement \u00e0 celles ou ceux qui ne connaissent pas encore \u2013 bouhhhh c\u2019est mal! \u2013 le <strong>Team Outdoor Poli<\/strong> de rattraper le retard. Cette ann\u00e9e, c\u2019est \u00e0 travers un portrait chinois que j\u2019ai propos\u00e9 \u00e0 mon \u00e9quipe que vous allez d\u00e9couvrir ou red\u00e9couvrir chaque athl\u00e8te du TEAM. Voici ce que notre benjamin du TOP, <strong>Nicolas DUHAIL<\/strong> nous r\u00e9v\u00e8le : <\/span><br class=\"none\"><br class=\"none\"><strong><span style=\"font-size: 12pt; color: #000000;\">1. Si tu \u00e9tais une course de ton ann\u00e9e 2016 ?<br class=\"none\"><\/span><\/strong><br \/>\n<span style=\"font-size: 12pt; color: #000000;\"><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/01_utmc.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-12154\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/01_utmc-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/01_utmc-300x200.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/01_utmc-768x512.jpg 768w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/01_utmc-1024x683.jpg 1024w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/01_utmc-600x400.jpg 600w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/01_utmc.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>L\u2019<strong>Ultra-Tour de la Motte-Chalancon<\/strong> (Grand Tour des Cr\u00eates \u2013 86km et 4500m D+), dans la Dr\u00f4me. Parce que c\u2019est la course o\u00f9 j\u2019ai pris le plus de plaisir cette ann\u00e9e, et je compte bien y retourner en 2017 ! Les passages sur les cr\u00eates sont grandioses avec des vues magnifiques. Pour une premi\u00e8re \u00e9dition, c\u2019\u00e9tait vraiment une organisation aux petits oignons.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-size: 12pt; color: #000000;\">2. Si tu \u00e9tais une paire de chaussures ?<br class=\"none\"><\/span><\/strong><br \/>\n<span style=\"font-size: 12pt; color: #000000;\"><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/02_xt4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-12155\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/02_xt4-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/02_xt4-300x192.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/02_xt4-768x492.jpg 768w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/02_xt4-600x384.jpg 600w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/02_xt4.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Ce serait l\u2019<strong>Adidas Adizero XT4<\/strong>. Une chaussure qui ne se fait plus, dont je n\u2019ai jamais retrouv\u00e9 l\u2019accroche et le dynamisme sur un autre mod\u00e8le. Je ne sais pas combien de paires j\u2019ai us\u00e9es, mais heureusement il me reste encore une paire neuve en cas d\u2019urgence.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-size: 12pt; color: #000000;\">3. Si tu \u00e9tais une des disciplines de la course \u00e0 pied ?<br class=\"none\"><\/span><\/strong><br \/>\n<span style=\"font-size: 12pt; color: #000000;\"><strong><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/03_kv.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-12156\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/03_kv-200x300.jpg\" alt=\"\" width=\"200\" height=\"300\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/03_kv-200x300.jpg 200w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/03_kv-768x1152.jpg 768w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/03_kv-683x1024.jpg 683w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/03_kv-600x900.jpg 600w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/03_kv.jpg 1365w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a>Le<\/strong> <strong>kilom\u00e8tre vertical<\/strong> : intense et exigeant ! Bien que je n\u2019en aie encore jamais fait, le principe de cette discipline me pla\u00eet beaucoup. Se faire exploser les poumons et arriver les cuisses en feu sur une belle mont\u00e9e s\u00e8che ! Il faut arriver bien pr\u00e9par\u00e9 pour affronter cette \u00e9preuve :)<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-size: 12pt; color: #000000;\">4. Si tu \u00e9tais une photo ?<br class=\"none\"><br class=\"none\"><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/04_paysage.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-12157\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/04_paysage-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/04_paysage-1024x683.jpg 1024w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/04_paysage-300x200.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/04_paysage-768x512.jpg 768w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/04_paysage-600x400.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><br class=\"none\"><\/span><\/strong><br \/>\n<span style=\"font-size: 12pt; color: #000000;\">Cette photo me rappelle combien nous sommes minuscules face \u00e0 l\u2019immensit\u00e9 de la nature. Mais pour avoir le privil\u00e8ge d\u2019\u00eatre spectateur d\u2019un paysage pareil, il faut le m\u00e9riter : cette photo a \u00e9t\u00e9 prise pendant l\u2019UTMB 2016, au sommet du Grand Col Ferret.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-size: 12pt; color: #000000;\">5. Si tu \u00e9tais une maxime ou un proverbe ?<br class=\"none\"><\/span><\/strong><br \/>\n<span style=\"font-size: 12pt; color: #000000;\"><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/05_kadoc.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-12158\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/05_kadoc-300x168.jpg\" alt=\"\" width=\"300\" height=\"168\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/05_kadoc-300x168.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/05_kadoc.jpg 492w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\u00ab <em>Pour savoir s\u2019il va y avoir du vent, il faut mettre son doigt dans le cul du coq<\/em>. \u00bb<\/span><br \/>\n<span style=\"font-size: 12pt; color: #000000;\">Brice Fournier<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #000000;\"><strong>6. Si tu \u00e9tais un livre ?<\/strong><br class=\"none\"><\/span><br \/>\n<span style=\"font-size: 12pt; color: #000000;\"><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/06_livre.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-12159\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/06_livre-194x300.jpg\" alt=\"\" width=\"194\" height=\"300\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/06_livre-194x300.jpg 194w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/06_livre.jpg 323w\" sizes=\"auto, (max-width: 194px) 100vw, 194px\" \/><\/a>Je ne suis pas tr\u00e8s orient\u00e9 litt\u00e9rature, donc difficile de citer un livre que j\u2019ai lu. Je vais donc me baser sur le titre et la description du bouquin. J\u2019ai donc choisi \u00ab <strong>L\u2019art de p\u00e9ter<\/strong> \u00bb, de Pierre-Thomas-Nicolas Hurtaut, un \u00e9rudit du XVIII\u00e8me si\u00e8cle, pour qui p\u00e9ter \u00e9tait un art et le pet, bien lanc\u00e9, une arme sociale. Il montre dans cet ouvrage toute la diversit\u00e9 des pets, qu\u2019il classe selon leur musicalit\u00e9, et d\u00e9crit les diff\u00e9rentes mani\u00e8res d\u2019en prolonger, d\u2019en moduler, ou d\u2019en minorer les sonorit\u00e9s. C\u2019est vraiment ma biographie en fait ;)<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-size: 12pt; color: #000000;\">7. Si tu \u00e9tais une montagne ?<br class=\"none\"><br class=\"none\"><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/07_piton_de_la_fournaise.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-12160\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/07_piton_de_la_fournaise-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/07_piton_de_la_fournaise-1024x683.jpg 1024w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/07_piton_de_la_fournaise-300x200.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/07_piton_de_la_fournaise-768x512.jpg 768w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/07_piton_de_la_fournaise-600x400.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><br class=\"none\"><\/span><\/strong><br \/>\n<span style=\"font-size: 12pt; color: #000000;\">Le Piton de la Fournaise, sur l\u2019\u00eele de la R\u00e9union. Car ce volcan peut tr\u00e8s bien rester endormi pendant des mois, puis avoir une activit\u00e9 d\u00e9bordante lorsqu\u2019il s\u2019\u00e9veille enfin. J\u2019esp\u00e8re bien aller le gravir, pourquoi pas d\u00e8s cette ann\u00e9e !<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-size: 12pt; color: #000000;\">8. Si tu \u00e9tais un sentiment ?<br class=\"none\"><\/span><\/strong><br \/>\n<span style=\"font-size: 12pt; color: #000000;\"><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/08_nico_grp.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-12161\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/08_nico_grp-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/08_nico_grp-300x225.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/08_nico_grp-768x576.jpg 768w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/08_nico_grp-1024x768.jpg 1024w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/08_nico_grp-600x450.jpg 600w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/08_nico_grp.jpg 1637w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>L\u2019<strong>impatience<\/strong> : je d\u00e9teste poireauter en attendant quelque chose qui ne d\u00e9pend pas de moi. J\u2019ai la phobie de perdre mon temps (et malheureusement \u00e7a peut vite me rendre irritable).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #000000;\"><strong>9. Si tu \u00e9tais une course \u00e0 faire absolument en 2017 ?<\/strong><br class=\"none\"><\/span><br \/>\n<span style=\"font-size: 12pt; color: #000000;\"><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/09_paella.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-12162\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/09_paella-300x199.jpg\" alt=\"\" width=\"300\" height=\"199\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/09_paella-300x199.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/09_paella-768x509.jpg 768w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/09_paella.jpg 1024w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/09_paella-600x397.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Ce serait le Trail du Josas, pour plusieurs raisons :<\/span><br \/>\n<span style=\"font-size: 12pt; color: #000000;\">&#8211;&nbsp;&nbsp; &nbsp;Le choix de distances (12km, 20km, 35km, 50km) permet de faire plaisir \u00e0 tous ;<\/span><br \/>\n<span style=\"font-size: 12pt; color: #000000;\">&#8211;&nbsp;&nbsp; &nbsp;Le parcours est tr\u00e8s sympa ;<\/span><br \/>\n<span style=\"font-size: 12pt; color: #000000;\">&#8211;&nbsp;&nbsp; &nbsp;Il fait toujours beau ;<\/span><br \/>\n<span style=\"font-size: 12pt; color: #000000;\">&#8211;&nbsp;&nbsp; &nbsp;On se retrouve tous \u00e0 l\u2019arriv\u00e9e avec bi\u00e8re et pa\u00eblla ;<\/span><br \/>\n<span style=\"font-size: 12pt; color: #000000;\">&#8211;&nbsp;&nbsp; &nbsp;La pa\u00eblla est excellente ;<\/span><br \/>\n<span style=\"font-size: 12pt; color: #000000;\">&#8211;&nbsp;&nbsp; &nbsp;La pa\u00eblla est d\u00e9licieuse ;<\/span><br \/>\n<span style=\"font-size: 12pt; color: #000000;\">&#8211;&nbsp;&nbsp; &nbsp;La pa\u00eblla d\u00e9chire sa race !<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-size: 12pt; color: #000000;\">10. Si tu \u00e9tais un(e) autre athl\u00e8te de la Team ?<br class=\"none\"><\/span><\/strong><br \/>\n<span style=\"font-size: 12pt; color: #000000;\"><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/10_tonio.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-12163\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/10_tonio-200x300.jpg\" alt=\"\" width=\"200\" height=\"300\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/10_tonio-200x300.jpg 200w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/10_tonio-768x1152.jpg 768w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/10_tonio-683x1024.jpg 683w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/10_tonio-600x900.jpg 600w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/10_tonio.jpg 1365w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a>Le choix est difficile mais je choisirais <strong>Tonio<\/strong>. En effet j\u2019ai toujours eu un petit faible pour sa copine ! Non je d\u00e9conne, c\u2019est plut\u00f4t pour ses horaires de prof et ses vacances \u00e0 rallonge. Et aussi parce que j\u2019aimerais bien savoir nager !<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-size: 12pt; color: #000000;\">11. Si tu \u00e9tais le P\u00e8re No\u00ebl ?<br class=\"none\"><\/span><\/strong><br \/>\n<span style=\"font-size: 12pt; color: #000000;\"><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/11_nico_noel.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-12164\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/11_nico_noel-300x243.jpg\" alt=\"\" width=\"300\" height=\"243\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/11_nico_noel-300x243.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/11_nico_noel-768x621.jpg 768w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/11_nico_noel-1024x828.jpg 1024w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/11_nico_noel-600x485.jpg 600w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/11_nico_noel.jpg 1323w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Cadeau unique pour tout le monde, comme \u00e7a pas de jaloux : une <strong>mandarine comme \u00e0 la belle \u00e9poque<\/strong> ! Et je garde tous les beaux cadeaux pour moi :)<\/span><br \/>\n<span style=\"font-size: 12pt; color: #000000;\">Et pour passer le temps en dehors de la p\u00e9riode de No\u00ebl, organiser des combats de rennes me para\u00eet judicieux.<br class=\"none\"><br class=\"none\"><strong><span style=\"font-size: 14pt;\">Nico<br class=\"none\"><br class=\"none\">R\u00c9SULTATS 2016<br class=\"none\"><br class=\"none\"><\/span><\/strong><\/span><span style=\"font-size: 12pt;\"><span style=\"color: #000000;\"><strong>L&rsquo;Hivernale<\/strong>, LES BREVIAIRES (78), 24km, 200mD+, 24\/01\/2016, 3\u00e8me, 01.36.07<\/span><span style=\"color: #000000;\"><br \/>\n<strong>MaxiCross de Bouff\u00e9mont<\/strong>, BOUFFEMONT (95), 42km, 1700mD+, 07\/02\/2016, 2\u00e8me, 03.23.26<br \/>\n<strong>Trail des Villes Royales<\/strong>, VERSAILLES (78), 53km, 1000mD+, 21\/02\/2016, 1er, 03.47.06<br \/>\n<strong>Trail d&rsquo;Auffargi<\/strong>s, AUFFARGIS (78), 33km, 1000mD+, 06\/03\/2016, 1er, 02.35.42<br \/>\n<strong>Trail des Flambeaux,<\/strong> MONTFORT-L\u2019AMAURY (78), 18km, 400mD+, 12\/03\/2016, 1er, 01.11.06<br \/>\n<strong>Ecotrail de Paris<\/strong>, PARIS (75), 80km, 1000mD+, 19\/03\/2016, 1er, 05.25.27<br \/>\n<strong>Trail du Josas<\/strong>, JOUY-EN-JOSAS (78), 35km, 800mD+, 10\/04\/2016, 2\u00e8me, 02.38.50<br \/>\n<strong>Trail des Lavoirs<\/strong>, CHEVREUSE (78), 53km, 1500mD+, 01\/05\/2016, 1er, 04.06.08<br \/>\n<strong>Trail des Cerfs<\/strong>, LA-QUEUE-LEZ-YVELINES (78), 35 km, 750mD+, 23\/05\/2016, 1er, 02.23.38<br \/>\n<strong>Grand Prix des Clayes<\/strong>, LES CLAYES-SOUS-BOIS (78), 10km, 03\/06\/2016, 2\u00e8me, 00.32.33<br \/>\n<strong>Trail du Vieux Lavoir<\/strong>, MORAINVILLIERS (78), 35km, 570m D+, 26\/06\/2016, 1er, 02.21.45<br \/>\n<strong>UTMC &#8211; Grand Tour des Cr\u00eates<\/strong>, LA MOTTE-CHALANCON (26), 86km, 4500m D+, 23\/07\/2016, 1er, 09.14.53<br \/>\n<strong>UTMC &#8211; Trail des Ruelles<\/strong>, LA MOTTE-CHALANCON (26), 25km, 1200m D+, 24\/07\/2016, 11\u00e8me, 04.49.16<br \/>\n<strong>GRP &#8211; Tour Des Cirques<\/strong>, VIELLE-AURE (65), 120km, 7000m D+, 26\/08\/2016, 1er, 17.32.00<br \/>\n<strong>Imperial Trail<\/strong>, FONTAINEBLEAU (77), 60km, 1500m D+, 17\/09\/2016, 1er, 05.30.04<br \/>\n<strong>Trail du Haut Planet<\/strong>, ADAINVILLE (78), 34km, 600m D+, 09\/10\/2016, 1er, 02.17.15<br \/>\n<strong>La Villepreusienne<\/strong>, VILLEPREUX (78), 10km, 16\/10\/2016, 2\u00e8me, 00.34.42<br \/>\n<strong>Le Grand Trail des Templiers<\/strong>, MILLAU (12), 76km, 3500m D+, 23\/10\/2016, 13\u00e8me, 07.21.01<br \/>\n<strong>Course Nocturne des Flambeaux<\/strong>, MONTFORT-L\u2019AMAURY (78), 18km, 450m D+, 12\/11\/2016, 1er, 01.12.35<br \/>\n<strong>Ultra-Trail de L\u2019Origole<\/strong>, LE PERRAY-EN-YVELINES (78), 110km, 3300m D+, 03-04\/12\/2016, 1er, 11.56.20<br \/>\n<strong>Corrida de la Saint-Sylvestre<\/strong>, CLERMONT-FERRAND (63), 7km, 30\/12\/2016, 6\u00e8me, 00.23.41<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une ann\u00e9e qui commence est traditionnellement l\u2019occasion de faire le point sur celle qui se termine et de se donner des objectifs. cela permet \u00e9galement \u00e0 celles ou ceux qui ne connaissent pas encore \u2013 bouhhhh c\u2019est mal! \u2013 le Team Outdoor Poli de rattraper le retard. Cette ann\u00e9e, c\u2019est \u00e0 travers un portrait chinois [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12168,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-12166","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-le-team-athletes-top","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"_links":{"self":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts\/12166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/comments?post=12166"}],"version-history":[{"count":3,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts\/12166\/revisions"}],"predecessor-version":[{"id":12171,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts\/12166\/revisions\/12171"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/media\/12168"}],"wp:attachment":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/media?parent=12166"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/categories?post=12166"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/tags?post=12166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}