{"id":12203,"date":"2017-01-20T14:50:37","date_gmt":"2017-01-20T13:50:37","guid":{"rendered":"http:\/\/www.team-outdoor.fr\/blog\/?p=12203"},"modified":"2017-01-20T14:55:32","modified_gmt":"2017-01-20T13:55:32","slug":"laurent-miklic-invite-top-2017-portrait-et-en-route-vers-2017","status":"publish","type":"post","link":"https:\/\/www.team-outdoor.fr\/blog\/laurent-miklic-invite-top-2017-portrait-et-en-route-vers-2017\/","title":{"rendered":"Laurent MIKLIC, invit\u00e9 TOP 2017 : portrait et en route vers 2017"},"content":{"rendered":"<p style=\"text-align: justify;\"><br class=\"none\"><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/photo_0_entete.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-12197\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/photo_0_entete.jpg\" alt=\"\" width=\"960\" height=\"672\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/photo_0_entete.jpg 960w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/photo_0_entete-300x210.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/photo_0_entete-768x538.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a><br class=\"none\"><br class=\"none\"><span style=\"font-size: 12pt; color: #000000;\">En d\u00e9cembre dernier, comme chaque ann\u00e9e maintenant depuis 5 ans, nous lancions l&rsquo;appel \u00e0 candidatures pour l&rsquo;<strong>invit\u00e9 TEAM 2017<\/strong>. Il s&rsquo;agit d\u2019accueillir au sein de l&rsquo;\u00e9quipe et ce pour une dur\u00e9e d&rsquo;un an, un(e) de nos client(e)s, supporter, habitu\u00e9 des veill\u00e9es, ami(e)s de divers horizons&#8230; Nous vous remercions pour les dossiers que nous avons re\u00e7u. 15 au total cette ann\u00e9e! \u00e7a nous touche beaucoup. Le plus compliqu\u00e9 alors pour nous est alors de choisir. Car c&rsquo;est comme \u00e0 Koh Lanta. A la fin, il ne doit en rester plus qu&rsquo;un! Nous avons ador\u00e9 d\u00e9couvrir vos r\u00e9cits, photos, anecdotes, montages vid\u00e9o, montages page internet, po\u00e8mes&#8230; Vous avez \u00e9t\u00e9 au TOP! Apr\u00e8s 10 jours de d\u00e9lib\u00e9ration, c&rsquo;est <strong>Laurent MIKLIC<\/strong> qui a \u00e9t\u00e9 choisi en tant qu&rsquo;invit\u00e9 TOP 2017. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #000000;\">Avant de le pr\u00e9senter \u00e0 travers son portrait chinois, voici un extrait de son dossier : <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #000000;\"><strong><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/2016-04-10-15.12.30.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-12204\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/2016-04-10-15.12.30-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/2016-04-10-15.12.30-225x300.jpg 225w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/2016-04-10-15.12.30-768x1024.jpg 768w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a>\u00ab\u00a04. Nous relater une anecdote de course qui vous a le plus marqu\u00e9.\u00a0\u00bb<\/strong> <\/span><br class=\"none\"><br class=\"none\"><span style=\"font-size: 12pt; color: #000000;\"><em>\u00ab\u00a0Cette ann\u00e9e, j\u2019ai particip\u00e9 pour la premi\u00e8re fois au trail du Josas sur le 50 km. Jonathan et Nicolas \u00e9taient inscrits sur le 30 km. Une partie du parcours \u00e9tait commune aux 2 distances. Dans une mont\u00e9e, je vois passer 2 fus\u00e9es jaunes et plus personne derri\u00e8re pendant de longues minutes. Par la suite, je me fais d\u00e9passer par d\u2019autres coureurs du 30 km. Certains d\u2019entre eux se retournent en me regardant. Sur le coup, je ne comprends pas tout de suite mais j\u2019ai l\u2019impression que certains sont \u00e9tonn\u00e9s d\u2019\u00eatre revenu sur un coureur aux couleurs du TOP et de le doubler.\u00a0\u00bb<\/em><br class=\"none\"><br class=\"none\">Laurent, merci pour ta confiance et Bienvenue au sein du Team Outdoor Poli<br class=\"none\"><br class=\"none\">Agn\u00e8s<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\"><strong><span style=\"color: #000000;\">Portrait Chinois de Laurent<\/span><\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #000000;\">&nbsp;<\/span><br \/>\n<strong><span style=\"font-size: 12pt; color: #000000;\">1. Si tu \u00e9tais une course de ton ann\u00e9e 2016 ?<br class=\"none\"><\/span><\/strong><br \/>\n<span style=\"font-size: 12pt; color: #000000;\"><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/photo_1_situetaisunecourse_1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-12198\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/photo_1_situetaisunecourse_1-300x199.jpg\" alt=\"\" width=\"300\" height=\"199\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/photo_1_situetaisunecourse_1-300x199.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/photo_1_situetaisunecourse_1-768x510.jpg 768w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/photo_1_situetaisunecourse_1-1024x680.jpg 1024w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/photo_1_situetaisunecourse_1.jpg 1848w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Le choix est difficile. Je retiendrai 2 courses pour la beaut\u00e9 des paysages.<br class=\"none\"><\/span><br \/>\n<span style=\"font-size: 12pt; color: #000000;\"><strong>Le trail du bout du Monde<\/strong> \u00e0 la pointe Saint-Mathieu en Bretagne : Je ne connaissais pas du tout la r\u00e9gion et ce trail m\u2019a permis de d\u00e9couvrir des c\u00f4tes magnifiques sous le soleil en plus (\u00e9tonnant non!!!) malgr\u00e9 tout de m\u00eame un petit crachin au d\u00e9part. Pour la petite anecdote : je terminais \u00e0 peine la premi\u00e8re boucle de 37 km, il me restait encore la boucle de 20 km et le speaker annon\u00e7ait d\u00e9j\u00e0 l\u2019arriv\u00e9e de Benoit Gandelot.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #000000;\"><strong>La MaxiRace \u00e0 Annecy<\/strong> : j\u2019ai beaucoup appr\u00e9ci\u00e9 l\u2019ambiance et les points de vue sur le lac avec le regret de pas avoir pu aller jusqu\u2019au bout.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-size: 12pt; color: #000000;\">2. Si tu \u00e9tais une paire de chaussures ?<a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/photo_2_situetaisunepairedechaussure.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-12200 alignright\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/photo_2_situetaisunepairedechaussure-169x300.jpg\" alt=\"\" width=\"169\" height=\"300\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/photo_2_situetaisunepairedechaussure-169x300.jpg 169w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/photo_2_situetaisunepairedechaussure-768x1365.jpg 768w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/photo_2_situetaisunepairedechaussure-576x1024.jpg 576w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/photo_2_situetaisunepairedechaussure.jpg 1494w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/><\/a><br class=\"none\"><\/span><\/strong><br \/>\n<span style=\"font-size: 12pt; color: #000000;\">Mes pieds sont d\u2019accord sur la marque mais pas sur le mod\u00e8le. <\/span><span style=\"font-size: 12pt; color: #000000;\">Mon pied droit serait la <strong>Glycerine<\/strong> et mon pied gauche la <strong>Cascadia<\/strong>, toutes deux de chez Brooks. Ils se sentent tr\u00e8s bien dans les 2.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-size: 12pt; color: #000000;\">3. Si tu \u00e9tais une des disciplines de la course \u00e0 pied?<br class=\"none\"><\/span><\/strong><br \/>\n<span style=\"font-size: 12pt; color: #000000;\">Le <strong>trail long<\/strong> (entre 40 et 80 km) pour ces longues heures d\u2019effort, avec ses moments de bien et de moins bien et o\u00f9 mon objectif est de terminer, peu importe le temps. <\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-size: 12pt; color: #000000;\">4. Si tu \u00e9tais une photo ?<br class=\"none\"><\/span><\/strong><br class=\"none\"><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/photo_4_situetaisunephoto.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-12201\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/photo_4_situetaisunephoto-1024x1024.jpg\" alt=\"\" width=\"1024\" height=\"1024\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/photo_4_situetaisunephoto-1024x1024.jpg 1024w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/photo_4_situetaisunephoto-150x150.jpg 150w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/photo_4_situetaisunephoto-300x300.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/photo_4_situetaisunephoto-768x768.jpg 768w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/photo_4_situetaisunephoto.jpg 1536w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><br \/>\n<span style=\"font-size: 12pt; color: #000000;\"><strong>Un belle rencontre \u00e0 Chamonix avec Kilian Jornet<\/strong>, il y a 3 ans avant le marathon du Mont-Blanc.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-size: 12pt; color: #000000;\">5. Si tu \u00e9tais une maxime ou un proverbe ?<\/span><\/strong><br \/>\n<span style=\"font-size: 12pt; color: #000000;\">\u00ab\u00a0<em>La ligne d&rsquo;arriv\u00e9e est toujours plus proche au fur et \u00e0 mesure que l&rsquo;on s&rsquo;en rapproche.<\/em>\u00ab\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-size: 12pt; color: #000000;\">6. Si tu \u00e9tais un livre ?<br class=\"none\"><\/span><\/strong><br \/>\n<span style=\"font-size: 12pt; color: #000000;\">\u00ab <strong>Courir : M\u00e9ditations physiques<\/strong> \u00bb de Guillaume le Blanc, professeur de philosophie et marathonien. <\/span><span style=\"font-size: 12pt; color: #000000;\">Pour celles et ceux qui apr\u00e8s avoir un dur entra\u00eenement physique, veulent faire chauffer leurs cellules grises, veulent savoir si il y a un lien entre la philosophie et la course \u00e0 pied, je vous conseille cet essai constitu\u00e9 de 42 chapitres autant que les kilom\u00e8tres d\u2019un marathon. Je vous avoue que j\u2019ai eu un peu de mal \u00e0 tout comprendre et qu\u2019il m\u2019a fallu un peu de temps pour en venir \u00e0 bout !!!!<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-size: 12pt; color: #000000;\"><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/photo_7_situetaisunemontagne.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-12202 alignleft\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/photo_7_situetaisunemontagne-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/photo_7_situetaisunemontagne-300x225.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/photo_7_situetaisunemontagne-768x576.jpg 768w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/photo_7_situetaisunemontagne-1024x768.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>7. Si tu \u00e9tais une montagne ?<br class=\"none\"><\/span><\/strong><br \/>\n<span style=\"font-size: 12pt; color: #000000;\"><strong>Bellec\u00f4te \u00e0 la Plagne<\/strong>. <\/span><span style=\"font-size: 12pt; color: #000000;\">Son ascension est beaucoup plus facile et rapide l\u2019hiver par les remont\u00e9es m\u00e9caniques avec des skis aux pieds que l\u2019\u00e9t\u00e9 pendant la 6000D. <\/span><span style=\"font-size: 12pt; color: #000000;\">Et que dire de la descente\u2026<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-size: 12pt; color: #000000;\">8. Si tu \u00e9tais un sentiment ?<br class=\"none\"><\/span><\/strong><br \/>\n<span style=\"font-size: 12pt; color: #000000;\"><strong>La joie d\u2019apr\u00e8s course<\/strong> : pour la sensation de pl\u00e9nitude, de s\u00e9r\u00e9nit\u00e9, de bien-\u00eatre apr\u00e8s avoir franchi la ligne d\u2019arriv\u00e9e malgr\u00e9 la fatigue\u2026<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-size: 12pt; color: #000000;\"><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/photo_1_situetaisunecourse_2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-12199\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/photo_1_situetaisunecourse_2-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/photo_1_situetaisunecourse_2-300x200.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/photo_1_situetaisunecourse_2-768x512.jpg 768w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/photo_1_situetaisunecourse_2-1024x683.jpg 1024w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/photo_1_situetaisunecourse_2.jpg 1776w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>9. Si tu \u00e9tais une course \u00e0 faire absolument en 2017 ?<br class=\"none\"><\/span><\/strong><br \/>\n<span style=\"font-size: 12pt; color: #000000;\"><strong>La MaxiRace<\/strong> : Apr\u00e8s mon \u00e9chec de l\u2019ann\u00e9e derni\u00e8re o\u00f9 j\u2019ai \u00e9t\u00e9 rattrap\u00e9 par Dame \u00ab barri\u00e8re horaire \u00bb, je n\u2019avais pas l\u2019intention de m\u2019y inscrire cette ann\u00e9e. Mais, faire parti de la Team Outdoor en tant qu\u2019invit\u00e9, m\u2019a re-boost\u00e9 et m\u2019a fait re-signer. <\/span><span style=\"font-size: 12pt; color: #000000;\">Cette ann\u00e9e, je n\u2019ai pas l\u2019intention de me laisser faire et de revoir cette dame.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-size: 12pt; color: #000000;\">10. Si tu \u00e9tais un(e) autre athl\u00e8te de la Team ?<br class=\"none\"><\/span><\/strong><br \/>\n<span style=\"font-size: 12pt; color: #000000;\">C\u2019est vrai qu\u2019il est peut-\u00eatre encore t\u00f4t et que je ne sais pas encore ce qui m\u2019attend vraiment, mais j\u2019ai l\u2019impression que je vais participer \u00e0 une aventure exceptionnelle avec tous les athl\u00e8tes de la Team. <\/span><span style=\"font-size: 12pt; color: #000000;\">C\u2019est donc l\u2019<strong>invit\u00e9 du TOP 2018<\/strong> que je souhaiterais \u00eatre, pour pouvoir continuer l\u2019aventure l\u2019ann\u00e9e prochaine.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-size: 12pt; color: #000000;\"><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/photo_11_situetaisleperenoel.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-12196\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/photo_11_situetaisleperenoel-269x300.jpg\" alt=\"\" width=\"269\" height=\"300\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/photo_11_situetaisleperenoel-269x300.jpg 269w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2017\/01\/photo_11_situetaisleperenoel.jpg 353w\" sizes=\"auto, (max-width: 269px) 100vw, 269px\" \/><\/a>11. Si tu \u00e9tais le P\u00e8re-No\u00ebl ?<br class=\"none\"><\/span><\/strong><br \/>\n<span style=\"font-size: 12pt; color: #000000;\">\u00ab\u00a0Si j\u2019\u00e9tais le P\u00e8re No\u00ebl, dit la petite boule blanche<\/span><br \/>\n<span style=\"font-size: 12pt; color: #000000;\">Je serais tout rose<\/span><br \/>\n<span style=\"font-size: 12pt; color: #000000;\">J\u2019aurais un manteau rouge<\/span><br \/>\n<span style=\"font-size: 12pt; color: #000000;\">J\u2019aurais des bottes noires<\/span><br \/>\n<span style=\"font-size: 12pt; color: #000000;\">Des gants blancs<\/span><br \/>\n<span style=\"font-size: 12pt; color: #000000;\">Un bonnet rouge et un pompon blanc<\/span><br \/>\n<span style=\"font-size: 12pt; color: #000000;\">Une barbe blanche<\/span><br \/>\n<span style=\"font-size: 12pt; color: #000000;\">Et j\u2019apporterais plein de cadeaux.\u00a0\u00bb<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #000000;\">(Comptine pour enfant)<br class=\"none\"><br class=\"none\"><strong>Laurent<\/strong><br class=\"none\"><br class=\"none\"><br class=\"none\"><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En d\u00e9cembre dernier, comme chaque ann\u00e9e maintenant depuis 5 ans, nous lancions l&rsquo;appel \u00e0 candidatures pour l&rsquo;invit\u00e9 TEAM 2017. Il s&rsquo;agit d\u2019accueillir au sein de l&rsquo;\u00e9quipe et ce pour une dur\u00e9e d&rsquo;un an, un(e) de nos client(e)s, supporter, habitu\u00e9 des veill\u00e9es, ami(e)s de divers horizons&#8230; Nous vous remercions pour les dossiers que nous avons re\u00e7u. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12199,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-12203","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-le-team-athletes-top","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"_links":{"self":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts\/12203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/comments?post=12203"}],"version-history":[{"count":7,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts\/12203\/revisions"}],"predecessor-version":[{"id":12211,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts\/12203\/revisions\/12211"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/media\/12199"}],"wp:attachment":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/media?parent=12203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/categories?post=12203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/tags?post=12203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}