{"id":13975,"date":"2019-05-27T19:05:52","date_gmt":"2019-05-27T18:05:52","guid":{"rendered":"https:\/\/www.team-outdoor.fr\/blog\/?p=13975"},"modified":"2020-11-12T20:53:51","modified_gmt":"2020-11-12T19:53:51","slug":"on-a-teste-pour-vous-la-hoka-one-one-evo-jawz-par-jonathan-duhail","status":"publish","type":"post","link":"https:\/\/www.team-outdoor.fr\/blog\/on-a-teste-pour-vous-la-hoka-one-one-evo-jawz-par-jonathan-duhail\/","title":{"rendered":"On a test\u00e9 pour vous la HOKA ONE ONE Evo Jawz par Jonathan DUHAIL"},"content":{"rendered":"\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Contexte<\/strong><\/h2>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color has-normal-font-size\">La chaussure de trail que j&rsquo;ai le plus kiff\u00e9e \u00e9tait, jusqu&rsquo;\u00e0 pr\u00e9sent, la <strong>ADIDAS XT4<\/strong>. Mais voil\u00e0, la marque aux trois bandes a d\u00e9j\u00e0 d\u00e9cid\u00e9 d&rsquo;arr\u00eater ce mod\u00e8le en pointure 49, puis de l&rsquo;arr\u00eater tout court. Lors que j&rsquo;ai aper\u00e7u la <strong>HOKA EVO JAWZ<\/strong> pour la premi\u00e8re fois au magasin, j&rsquo;ai tout de suite \u00e9t\u00e9 bluff\u00e9 : elle me rappelle fortement la XT4 avec un drop plus faible mais une semelle l\u00e9g\u00e8rement plus \u00e9paisse. J&rsquo;ai vite demand\u00e9 \u00e0 Agn\u00e8s si elle existait en 49. Me connaissant bien, elle en avait pr\u00e9command\u00e9 une paire en cette pointure. J&rsquo;avais encore plus h\u00e2te de reprendre la course \u00e0 pied ! <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/thumbnail_IMG_5505-1024x682.jpg\" alt=\"\" class=\"wp-image-13965\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/thumbnail_IMG_5505-1024x682.jpg 1024w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/thumbnail_IMG_5505-300x200.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/thumbnail_IMG_5505-768x512.jpg 768w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/thumbnail_IMG_5505.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-media-text alignwide\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/2017-11-29-17.04.16-1024x768.jpg\" alt=\"\" class=\"wp-image-13977\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/2017-11-29-17.04.16-1024x768.jpg 1024w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/2017-11-29-17.04.16-300x225.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/2017-11-29-17.04.16-768x576.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h2 class=\"wp-block-heading\"><strong>Le look<\/strong><\/h2>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color has-normal-font-size\">Cette chaussure interpelle tout de suite&nbsp;: elle est hyper rac\u00e9e, tr\u00e8s fine, mais avec des gros crampons&nbsp;: assez d\u00e9cal\u00e9e du style habituel d\u2019HOKA ONE ONE.<\/p>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color has-normal-font-size\">La semelle semble bien \u00e0 plat (drop 3mm) et est dot\u00e9e de crampons assez imposants (6mm). <\/p>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color has-normal-font-size\">Aucune couture, des lacets parfaitement positionn\u00e9s avec des trous en longueurs et pas ronds, et un mat\u00e9riau (<strong>MATRIX<\/strong>) pour le mesh ultra r\u00e9sistant, \u00e7a s\u2019annonce pas mal&nbsp;!<\/p>\n<\/div><\/div>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color has-normal-font-size\">Parfait pour pouvoir m&rsquo;accompagner dans ma reprise de la course  apr\u00e8s mes deux ann\u00e9es de gal\u00e8re. En effet, elle correspond pile poil aux crit\u00e8res donn\u00e9s par mon podologue : une semelle pas trop \u00e9paisse pour \u00e9viter l&rsquo;affaissement, une chaussure \u00e0 drop r\u00e9duit, une chaussure en laquelle j&rsquo;ai toute confiance avec ce pied qui me semble encore un peu \u00ab&nbsp;bizarre&nbsp;\u00bb ou instable&#8230;<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/2018-04-10-13.58.16-1024x768.jpg\" alt=\"\" data-id=\"13979\" data-link=\"https:\/\/www.team-outdoor.fr\/blog\/?attachment_id=13979\" class=\"wp-image-13979\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/2018-04-10-13.58.16-1024x768.jpg 1024w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/2018-04-10-13.58.16-300x225.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/2018-04-10-13.58.16-768x576.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/2018-04-10-13.58.20-1024x768.jpg\" alt=\"\" data-id=\"13980\" data-link=\"https:\/\/www.team-outdoor.fr\/blog\/?attachment_id=13980\" class=\"wp-image-13980\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/2018-04-10-13.58.20-1024x768.jpg 1024w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/2018-04-10-13.58.20-300x225.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/2018-04-10-13.58.20-768x576.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/2018-04-10-13.58.33-1024x768.jpg\" alt=\"\" data-id=\"13981\" data-link=\"https:\/\/www.team-outdoor.fr\/blog\/?attachment_id=13981\" class=\"wp-image-13981\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/2018-04-10-13.58.33-1024x768.jpg 1024w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/2018-04-10-13.58.33-300x225.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/2018-04-10-13.58.33-768x576.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/2018-04-10-13.58.45-1024x768.jpg\" alt=\"\" data-id=\"13983\" data-link=\"https:\/\/www.team-outdoor.fr\/blog\/?attachment_id=13983\" class=\"wp-image-13983\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/2018-04-10-13.58.45-1024x768.jpg 1024w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/2018-04-10-13.58.45-300x225.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/2018-04-10-13.58.45-768x576.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/2018-04-10-13.58.52-1024x768.jpg\" alt=\"\" data-id=\"13985\" data-link=\"https:\/\/www.team-outdoor.fr\/blog\/?attachment_id=13985\" class=\"wp-image-13985\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/2018-04-10-13.58.52-1024x768.jpg 1024w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/2018-04-10-13.58.52-300x225.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/2018-04-10-13.58.52-768x576.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/2018-04-10-13.59.12-1024x768.jpg\" alt=\"\" data-id=\"13986\" data-link=\"https:\/\/www.team-outdoor.fr\/blog\/?attachment_id=13986\" class=\"wp-image-13986\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/2018-04-10-13.59.12-1024x768.jpg 1024w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/2018-04-10-13.59.12-300x225.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/2018-04-10-13.59.12-768x576.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Les Caract\u00e9ristiques techniques<\/strong><\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color has-normal-font-size\">Fid\u00e8le \u00e0 son concept, la marque HOKA ONE ONE propose une chaussure avec u<strong>n drop r\u00e9duit, ici de 3mm<\/strong>. Pour autant, sur ce mod\u00e8le l&rsquo; \u00ab <strong>Oversize<\/strong>\u00a0\u00bb propre \u00e0 HOKA n&rsquo;est plus de mise. La semelle est \u00ab\u00a0r\u00e9duite\u00a0\u00bb par rapport aux autres mod\u00e8les de la marque. Elle offre, cependant, une protection cons\u00e9quente gr\u00e2ce \u00e0 la <strong>technologie ProFly<\/strong> alliant <strong>Pro<\/strong>tection et <strong>Pro<\/strong>pulsion.<\/p>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color has-normal-font-size\"><strong>Le poids est annonc\u00e9 \u00e0 212g en 42 2\/3<\/strong>. Je p\u00e8se 258g pour ma chaussure en pointure 49. Pour comparer, une <strong>NEW BALANCE ZANTE<\/strong> en 49 p\u00e8se 306g et une <strong>ASICS DS TRAINER 23<\/strong> en 49 p\u00e8se 286g. La HOKA EVO JAWZ est donc vraiment l\u00e9g\u00e8re pour une chaussure de trail, dans la lign\u00e9e de la <strong>SALOMON S-LAB SENSE<\/strong>. <\/p>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color has-normal-font-size\">Cette chaussure ne pr\u00e9sente pas de pare-pierre, le mesh est au plus pr\u00e8s du pied. Mais il s&rsquo;agit d&rsquo;un mesh sp\u00e9cifiquement d\u00e9velopp\u00e9 pour \u00eatre r\u00e9sistant, le <strong>mesh MATRIX<\/strong>. Seul inconv\u00e9nient sur la EVO JAWZ, avec l&rsquo;humidit\u00e9 il donne des pieds bleus (update 01\/2020 : pb corrig\u00e9). <\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide has-media-on-the-right\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"632\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/2018-04-10-22.30.17-2-1024x632.jpg\" alt=\"\" class=\"wp-image-14001\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/2018-04-10-22.30.17-2-1024x632.jpg 1024w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/2018-04-10-22.30.17-2-300x185.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/2018-04-10-22.30.17-2-768x474.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-very-light-gray-color has-vivid-cyan-blue-background-color has-text-color has-background has-normal-font-size\">Les <strong>crampons de 6mm<\/strong> positionn\u00e9s sur la semelle <strong>VIBRAM<\/strong> promettent une  accroche en toute circonstance et sur tous les terrains, mais  l\u2019adh\u00e9rence n\u2019est pas laiss\u00e9e de c\u00f4t\u00e9 pour autant, puisque le mat\u00e9riau  utilis\u00e9 par Vibram est \u00e0 ultra haute adh\u00e9rence m\u00eame sur rochers  mouill\u00e9s. Tout ceci explique pourquoi cette chaussure est tant appr\u00e9ci\u00e9e  par les adeptes du <strong>Swim-Run<\/strong>, \u00e0 condition que des pieds bleus ne les rebutent pas donc ;) <\/p>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Enfilage de la chaussure<\/strong><\/h2>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color has-normal-font-size\">Comme pour quasiment toutes mes chaussures, j\u2019ai pris du 14US, soit 49 1\/3 chez Hoka. Le taillant est parfait pour moi. La chaussure est <strong>tr\u00e8s proche du pied<\/strong>. Bon, avec de tels pieds, je dois desserrer un peu les lacets pour entrer le pied dedans. On se rend compte en la prenant en main que la chaussure est extr\u00eamement souple&nbsp;: pas de renforts superflus ou de semelle tr\u00e8s rigide, le pied sera vraiment libre.<\/p>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color has-normal-font-size\">Une fois le pied \u00e0 l\u2019int\u00e9rieur, <strong>je me sens tout de suite \u00e0 l\u2019aise<\/strong>, \u00ab&nbsp;comme \u00e0 la maison&nbsp;\u00bb&nbsp;! Le mesh est tr\u00e8s pr\u00e8s du pied, la chaussure est souple et aucune g\u00eane n\u2019est ressentie. La languette est, elle aussi, tr\u00e8s minimaliste, tr\u00e8s peu \u00e9paisse, juste un peu rembourr\u00e9e pour pas que les lacets ne serrent directement le coup de pied.<\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/2018-04-10-13.58.20-1024x768.jpg\" alt=\"\" class=\"wp-image-13980\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/2018-04-10-13.58.20-1024x768.jpg 1024w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/2018-04-10-13.58.20-300x225.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/2018-04-10-13.58.20-768x576.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-very-light-gray-color has-vivid-cyan-blue-background-color has-text-color has-background has-normal-font-size\"><strong>Les lacets<\/strong> sont aussi une vrai r\u00e9ussite ! Ce sont des lacets plats,  la longueur est parfaite et ils ne se sont pas d\u00e9faits une seule fois en  5 mois d\u2019utilisation. Le gros plus ce sont les trous de passage qui  sont en fente plate, comme le lacet, pour que celui-ci ne bouge pas une fois pass\u00e9 dedans. <\/p>\n<\/div><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color has-normal-font-size\"><strong>Les crampons ne se ressentent pas en mettant la chaussure, il faudra voir \u00e0 l\u2019utilisation. En tout cas, \u00e0 peine apr\u00e8s avoir mis le pied dedans, je suis emball\u00e9 comme rarement en mettant une chaussure de trail&nbsp;!<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Test sur le terrain<\/strong><\/h2>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color has-normal-font-size\">Lors de la reprise\nen janvier 2019, apr\u00e8s 4 mois sans courir, je n\u2019ai pas envie de faire n\u2019importe\nquoi, donc je reprends vraiment progressivement avec au d\u00e9but uniquement 2 \u00e0 3\nsorties par semaine vraiment cools.<\/p>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color has-normal-font-size\">Comme pr\u00e9vu, la\nchaussure se fait tout de suite oublier une fois au pied. Elle est vraiment\ntr\u00e8s l\u00e9g\u00e8re et le confort du chausson m\u2019a impressionn\u00e9 d\u00e8s la premi\u00e8re sortie.<\/p>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color has-normal-font-size\">J\u2019ai couru avec dans les montagnes aux alentours du Sancy pour commencer et j\u2019ai \u00e9t\u00e9 tr\u00e8s \u00e0 l\u2019aise tout de suite, que ce soit en mont\u00e9e ou en descente.<\/p>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color has-normal-font-size\">J\u2019ai ensuite couru\nenviron 800km avec en 5 mois surtout sur les chemins des Yvelines. L\u2019usure des\ncrampons est raisonnable au vu de la souplesse de la gomme faite pour adh\u00e9rer\nen toute circonstance. Le mesh lui n\u2019a pas boug\u00e9, il ne semble pas vieillir.<\/p>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color has-normal-font-size\">Dans la neige,\nj\u2019ai \u00e9t\u00e9 bluff\u00e9&nbsp;: la chaussure n\u2019a pas gliss\u00e9 une seule fois, que ce soit\ndans la neige fraiche ou dans la soupe un peu verglac\u00e9e quelques jours apr\u00e8s.\nPour les trails blancs \u00e7a semble \u00eatre une alli\u00e9e parfaite.<\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide has-media-on-the-right\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/thumbnail_IMG_5521-1024x682.jpg\" alt=\"\" class=\"wp-image-13967\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/thumbnail_IMG_5521-1024x682.jpg 1024w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/thumbnail_IMG_5521-300x200.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/thumbnail_IMG_5521-768x512.jpg 768w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/thumbnail_IMG_5521.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-very-light-gray-color has-vivid-cyan-blue-background-color has-text-color has-background has-normal-font-size\">J\u2019ai couru avec aussi bien par temps humide que par temps tr\u00e8s sec  tellement j\u2019\u00e9tais bien dedans. Aucune g\u00eane, aucun frottement, m\u00eame sur  terrain tr\u00e8s sec et ce malgr\u00e9 les gros crampons. Dans la boue, la  chaussure est magique, elle \u00e9vacue extr\u00eamement bien et accroche toujours  m\u00eame sur terrain hyper gras. <\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide has-media-on-the-right\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"732\" height=\"489\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/01..jpg\" alt=\"\" class=\"wp-image-13973\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/01..jpg 732w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/01.-300x200.jpg 300w\" sizes=\"auto, (max-width: 732px) 100vw, 732px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-very-light-gray-color has-vivid-cyan-blue-background-color has-text-color has-background has-normal-font-size\"> Je me suis dit aussi que les gens qui ne voulaient pas investir dans  <strong>une  paire de pointes pour faire les cross<\/strong> pouvaient tr\u00e8s bien utiliser   cette chaussure, certes un peu plus lourde, mais plus rassurante pour   certains.  <\/p>\n<\/div><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color has-normal-font-size\">La <strong>respirabilit\u00e9<\/strong> est parfaite et la chaussure permet aussi d\u2019\u00e9vacuer tr\u00e8s rapidement l\u2019eau qui rentre. Un d\u00e9faut cependant&nbsp;: la languette d\u00e9teint sur les chaussettes et sur les pieds d\u00e8s qu\u2019elle prend l\u2019humidit\u00e9. Je me suis retrouv\u00e9 r\u00e9guli\u00e8rement avec des pieds de Schtroumpfs.<\/p>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color has-normal-font-size\">Au niveau des\nsensations de course, on est vraiment sur une foul\u00e9e hyper naturelle avec le\npied vraiment libre tellement la chaussure est souple. On est vraiment proche\ndes sensations d\u2019une chaussure de route mais avec des gros crampons&nbsp;!<\/p>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color has-normal-font-size\">La chaussure est\ntr\u00e8s dynamique et on prend vraiment plaisir \u00e0 jouer avec le terrain\nd\u2019entrainement.<\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/20190512_105822-e1559234625377-768x1024.jpg\" alt=\"\" class=\"wp-image-13963\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/20190512_105822-e1559234625377-768x1024.jpg 768w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2019\/05\/20190512_105822-e1559234625377-225x300.jpg 225w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-very-light-gray-color has-vivid-cyan-blue-background-color has-text-color has-background has-normal-font-size\">Avant de publier ce petit test je l\u2019ai aussi test\u00e9e sur les deux comp\u00e9titions de reprise que j\u2019ai faites&nbsp;: le <strong>Trail du Josas et le Trail des Lavoirs<\/strong>.  Ce sont deux trails tr\u00e8s sympas dans les Yvelines. L\u2019un \u00e9tait tr\u00e8s sec  et l\u2019autre tr\u00e8s humide et dans les deux cas j\u2019ai pris un plaisir fou \u00e0  courir avec cette paire de chaussures. Elles se font oublier et sur des  parcours de 16 et 23 kms j\u2019ai vraiment appr\u00e9ci\u00e9 de les avoir aux pieds. <\/p>\n<\/div><\/div>\n\n\n\n<div style=\"height:51px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color\" style=\"font-size:clamp(14px, 0.875rem + ((1vw - 3.2px) * 0.313), 18px);px\"><strong>\u00c9tant donn\u00e9 que je gal\u00e8re toujours \u00e0 trouver ma pointure j\u2019ai demand\u00e9 \u00e0 Agn\u00e8s de commander plusieurs paires d\u2019avance tellement je suis fan&nbsp;!<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Bilan<\/strong><\/h2>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color has-normal-font-size\">Une chaussure \u00e0 avoir absolument! Elle permet de se faire plaisir en courant et de retrouver une libert\u00e9 de pied qui n\u2019existe pas dans beaucoup d\u2019autres chaussures. Le confort est au rendez-vous malgr\u00e9 le poids tr\u00e8s r\u00e9duit et on peut l\u2019utiliser sur des terrains plut\u00f4t vari\u00e9s malgr\u00e9 les crampons tr\u00e8s prononc\u00e9s.<\/p>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color has-normal-font-size\">HOKA a r\u00e9ussi <strong>une vraie innovation<\/strong> avec cette chaussure l\u00e9g\u00e8re, polyvalente, dynamique et r\u00e9active sur tous les terrains.<\/p>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color has-normal-font-size\">Le probl\u00e8me de <strong>d\u00e9coloration<\/strong> des languettes sur les chaussettes et les pieds d\u00e8s qu\u2019on court sur terrain humide a \u00e9t\u00e9 corrig\u00e9 sur les derni\u00e8res versions de la chaussure.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Points + <\/strong><\/h2>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color has-normal-font-size\">Chaussure ultra l\u00e9g\u00e8re,<\/p>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color has-normal-font-size\">Chausson confortable et proche du pied,<\/p>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color has-normal-font-size\">Polyvalence sur de tr\u00e8s nombreux terrains,<\/p>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color has-normal-font-size\">Mesh ind\u00e9chirable, ultra respirant et agr\u00e9able au pied,<\/p>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color has-normal-font-size\">Drop r\u00e9duit de 3mm,<\/p>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color has-normal-font-size\">Accroche impossible \u00e0 prendre \u00e0 d\u00e9faut,<\/p>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color has-normal-font-size\">Adh\u00e9rence impeccable en toutes situations,<\/p>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color has-normal-font-size\">R\u00e9activit\u00e9 et dynamisme.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Points &#8211; <\/strong><\/h2>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color has-normal-font-size\">Dur\u00e9e de vie des crampons sur des terrains abrasifs, mais on ne peut pas avoir une adh\u00e9rence parfaite et des crampons inusables,<\/p>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color has-normal-font-size\">Languettes qui d\u00e9teignent sur les chaussettes et les pieds. (Probl\u00e8me corrig\u00e9 par Hoka sur les derni\u00e8res versions).<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Pour vous les procurer (mais laissez-moi les pointures 49!)<\/strong><\/h2>\n\n\n\n<p class=\"has-very-dark-gray-color has-pale-cyan-blue-background-color has-text-color has-background\" style=\"font-size:clamp(14px, 0.875rem + ((1vw - 3.2px) * 0.313), 18px);px\"><strong>Mod\u00e8le Homme<\/strong> : <a href=\"https:\/\/www.team-outdoor.fr\/chaussures-homme\/5466-274015-hoka-one-one-evo-jawz-homme-cyan-citrus.html\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.team-outdoor.fr\/chaussures-homme\/5466-274015-hoka-one-one-evo-jawz-homme-cyan-citrus.html<\/a><\/p>\n\n\n\n<p class=\"has-very-dark-gray-color has-pale-cyan-blue-background-color has-text-color has-background\" style=\"font-size:clamp(14px, 0.875rem + ((1vw - 3.2px) * 0.313), 18px);px\"><strong>Mod\u00e8le Femme<\/strong> : <a href=\"https:\/\/www.team-outdoor.fr\/chaussures-femme\/5891-277960-hoka-one-one-evo-jawz-femme-cyan-citrus.html\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.team-outdoor.fr\/chaussures-femme\/5891-277960-hoka-one-one-evo-jawz-femme-cyan-citrus.html<\/a><\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Jonathan<\/strong><\/h2>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Contexte La chaussure de trail que j&rsquo;ai le plus kiff\u00e9e \u00e9tait, jusqu&rsquo;\u00e0 pr\u00e9sent, la ADIDAS XT4. Mais voil\u00e0, la marque aux trois bandes a d\u00e9j\u00e0 d\u00e9cid\u00e9 d&rsquo;arr\u00eater ce mod\u00e8le en pointure 49, puis de l&rsquo;arr\u00eater tout court. Lors que j&rsquo;ai aper\u00e7u la HOKA EVO JAWZ pour la premi\u00e8re fois au magasin, j&rsquo;ai tout de suite [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14015,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-13975","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-on-a-teste-pour-vous","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"_links":{"self":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts\/13975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/comments?post=13975"}],"version-history":[{"count":27,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts\/13975\/revisions"}],"predecessor-version":[{"id":15376,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts\/13975\/revisions\/15376"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/media\/14015"}],"wp:attachment":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/media?parent=13975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/categories?post=13975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/tags?post=13975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}