{"id":14914,"date":"2020-03-14T05:26:00","date_gmt":"2020-03-14T04:26:00","guid":{"rendered":"https:\/\/www.team-outdoor.fr\/blog\/?p=14914"},"modified":"2020-05-11T07:14:35","modified_gmt":"2020-05-11T06:14:35","slug":"fermeture-covid-19-prenez-soin-de-vous-soutenez-nous-en-ligne","status":"publish","type":"post","link":"https:\/\/www.team-outdoor.fr\/blog\/fermeture-covid-19-prenez-soin-de-vous-soutenez-nous-en-ligne\/","title":{"rendered":"Fermeture &#8211; Covid-19 &#8211; Prenez soin de vous &#038; soutenez-nous en ligne"},"content":{"rendered":"\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"680\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2020\/03\/552.-1024x680.jpg\" alt=\"\" class=\"wp-image-14915\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2020\/03\/552.-1024x680.jpg 1024w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2020\/03\/552.-300x199.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2020\/03\/552.-768x510.jpg 768w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2020\/03\/552.-1536x1020.jpg 1536w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2020\/03\/552..jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-color has-medium-font-size has-very-dark-gray-color\">  &#x1f1eb;&#x1f1f7;    Pour aller plus loin dans la r\u00e9flexion citoyenne pour remporter ce CLM contre le covid-19  &#x1f1eb;&#x1f1f7;   <\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-color has-normal-font-size has-very-dark-gray-color\"> <strong>Chers clientes, chers clients,<br> Ch\u00e8res amies, chers amis qui me soutenez \u00e0 chaque grosse difficult\u00e9 professionnelle  rencontr\u00e9e depuis presque 11 ans,<\/strong><\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-color has-normal-font-size has-very-dark-gray-color\">Tout d&rsquo;abord, nous esp\u00e9rons que vous et vos proches vous portez bien.<br><br>Conform\u00e9ment aux directives de notre gouvernement, notre magasin TEAM OUTDOOR est ferm\u00e9 jusqu&rsquo;\u00e0 nouvel ordre.<br><br><strong> Pour toutes celles et ceux qui souhaitent nous rester fid\u00e8les et,  n&rsquo;ayant pas peur des mots, nous aider \u00e0 continuer d&rsquo;exister, notre site  internet : <a rel=\"noreferrer noopener\" aria-label=\"www.team-outdoor.fr (s\u2019ouvre dans un nouvel onglet)\" href=\"http:\/\/www.team-outdoor.fr\" target=\"_blank\">www.team-outdoor.fr<\/a><a rel=\"noreferrer noopener\" href=\"https:\/\/l.facebook.com\/l.php?u=http%3A%2F%2Fwww.team-outdoor.fr%2F%3Ffbclid%3DIwAR1uflxfaiuJ9Ru_5meT3MHAEVgfOiCVGp_sGDRf08dnd9G1jt6X4PbluSA&amp;h=AT2K3ikfNpAT0cOaRrnkBMLyGvp_OtEeVy0juee0Ifj3HyCJ6Cb2nfwxHo9nSz3WvqAJ5kUfzSwkxjA9AyZvBKxRVAd-M8sjc-JhSyBbtR3ZaqtiiDJvLn_f2I13PUzJ7Pg8PBE\" target=\"_blank\">.<\/a> Merci infiniment par avance. <\/strong><\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p style=\"font-size:14px\" class=\"has-text-color has-very-dark-gray-color\"> A titre personnel, je comprends et f\u00e9licite cette d\u00e9cision de la part  de notre gouvernement. La sant\u00e9 de tous n&rsquo;a pas de prix. Aujourd&rsquo;hui,  c&rsquo;est \u00e0 la fois un sentiment d&rsquo;apaisement. On nous dicte l&rsquo;unique choix  citoyen qu&rsquo;il est tr\u00e8s difficile de faire soi-m\u00eame en tant  qu&rsquo;entrepreneur. Et une  angoisse intense par rapport \u00e0 l&rsquo;avenir de ma  soci\u00e9t\u00e9. Ma priorit\u00e9 \u00e9conomique sera de prot\u00e9ger mes salari\u00e9s. Place \u00e0  de longues d\u00e9marches administratives en esp\u00e9rant qu&rsquo;elles aboutissent.  Un autre genre d&rsquo;ultra commence.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-color has-normal-font-size has-very-dark-gray-color\"><strong>En attendant de se retrouver  chez TO pour f\u00eater la victoire contre le covid-19, prenez soin de vous  et de vos proches. RESPECTEZ LES CONSIGNES SANITAIRES qu&rsquo;on n&rsquo;ait pas  fait cela pour rien, je vous en prie. Soyez RESPONSABLES.<\/strong><br><br> Agn\u00e8s, g\u00e9rante de TEAM OUTDOOR<br><br><a href=\"https:\/\/www.facebook.com\/hashtag\/civisme?epa=HASHTAG\">#civisme<\/a><br><a href=\"https:\/\/www.facebook.com\/hashtag\/solidarit\u00e9?epa=HASHTAG\">#solidarit\u00e9<\/a><br><a href=\"https:\/\/www.facebook.com\/hashtag\/citoyennet\u00e9?epa=HASHTAG\">#citoyennet\u00e9<\/a><br><a href=\"https:\/\/www.facebook.com\/hashtag\/soutien?epa=HASHTAG\">#soutien<\/a><br><a href=\"https:\/\/www.facebook.com\/hashtag\/peur?epa=HASHTAG\">#peur<\/a><br><a href=\"https:\/\/www.facebook.com\/hashtag\/ensemble?epa=HASHTAG\">#ensemble<\/a><br><a href=\"https:\/\/www.facebook.com\/hashtag\/responsabilit\u00e9?epa=HASHTAG\">#responsabilit\u00e9<\/a><br><a href=\"https:\/\/www.facebook.com\/hashtag\/covid19?epa=HASHTAG\">#covid19<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#x1f1eb;&#x1f1f7; Pour aller plus loin dans la r\u00e9flexion citoyenne pour remporter ce CLM contre le covid-19 &#x1f1eb;&#x1f1f7; Chers clientes, chers clients, Ch\u00e8res amies, chers amis qui me soutenez \u00e0 chaque grosse difficult\u00e9 professionnelle rencontr\u00e9e depuis presque 11 ans, Tout d&rsquo;abord, nous esp\u00e9rons que vous et vos proches vous portez bien. Conform\u00e9ment aux directives de notre [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14915,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-14914","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveau-chez-to","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"_links":{"self":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts\/14914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/comments?post=14914"}],"version-history":[{"count":3,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts\/14914\/revisions"}],"predecessor-version":[{"id":14918,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts\/14914\/revisions\/14918"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/media\/14915"}],"wp:attachment":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/media?parent=14914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/categories?post=14914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/tags?post=14914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}