{"id":1493,"date":"2012-09-12T15:52:50","date_gmt":"2012-09-12T14:52:50","guid":{"rendered":"http:\/\/www.team-outdoor.fr\/blog\/?p=1493"},"modified":"2013-05-18T12:35:55","modified_gmt":"2013-05-18T11:35:55","slug":"on-a-teste-pour-vous-la-salomon-speed-cross-3","status":"publish","type":"post","link":"https:\/\/www.team-outdoor.fr\/blog\/on-a-teste-pour-vous-la-salomon-speed-cross-3\/","title":{"rendered":"On a test\u00e9 pour vous la SALOMON Speed Cross 3"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><span style=\"font-size: 20px; color: #ff6600;\">par Thierry QUICROIT, conseiller vente Team Outdoor, juillet &#8211; Aout 2011<br class=\"none\" \/><\/span><br \/>\n<\/strong><\/div>\n<p style=\"text-align: justify;\" align=\"center\"><span style=\"font-size: 14px; color: #000000;\">Apr\u00e8s ma premi\u00e8re r\u00e9elle saison trail et avoir us\u00e9 mes <strong>SALOMON S-LAB 3<\/strong> et\u00a0mes <strong>BROOKS CASCADIA 6<\/strong> jusqu&rsquo;\u00e0 la disparition de tous les crampons, je me\u00a0suis d\u00e9cid\u00e9 \u00e0 passer sur les <strong>SALOMON SPEED CROSS 3 CS<\/strong>.<\/span><\/p>\n<div id='gallery-1' class='gallery galleryid-1493 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.team-outdoor.fr\/blog\/pe13-salomon-speedcross-3-homme-p\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/PE13-SALOMON-SPEEDCROSS-3-Homme-p-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-1511\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-1511'>\n\t\t\t\tmod\u00e8le homme 2013\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.team-outdoor.fr\/blog\/pe13-salomon-speedcross-3-femme-p\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/PE13-SALOMON-SPEEDCROSS-3-femme-p-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-1510\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-1510'>\n\t\t\t\tmod\u00e8le femme 2013\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.team-outdoor.fr\/blog\/on-a-teste-pour-vous-la-salomon-speed-cross-3\/sc3-cs-1\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/SC3-CS-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-1494\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-1494'>\n\t\t\t\tmod\u00e8le homme CS 2012\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.team-outdoor.fr\/blog\/on-a-teste-pour-vous-la-salomon-speed-cross-3\/sc3-cs-12\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/SC3-CS-12-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-1505\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-1505'>\n\t\t\t\tmod\u00e8le femme 2012\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<div style=\"text-align: justify;\" align=\"center\"><span style=\"font-size: 14px; color: #000000;\"> Pour ceux qui connaissent les deux versions\u00a0pr\u00e9c\u00e9dentes, de l\u2019ext\u00e9rieur on ne remarque pas de changement. Mais, en r\u00e9alit\u00e9 la semelle interm\u00e9diaire a \u00e9t\u00e9 totalement retravaill\u00e9e pour rendre la chaussure plus \u00ab\u00a0neutre\u00a0\u00bb. Une autre nouveaut\u00e9, la version <strong>CS<\/strong> ou <strong>Clima Shield<\/strong> de la <strong>SPEED CROSS 3<\/strong>\u00a0; Clima Shield est le nom de la nouvelle membrane r\u00e9sistante \u00e0 l\u2019eau d\u00e9velopp\u00e9e par SALOMON. Elle est adjointe au mesh sur l\u2019avant de la chaussure, laissant le talon en mesh simple. Comme cela, la chaussure est imperm\u00e9able sur l\u2019avant mais reste respirante au niveau de la cheville. Pour autant, et malgr\u00e9 la membrane, <strong><strong>la chaussure demeure l\u00e9g\u00e8re<\/strong> <\/strong>(296g en 42). Enfin, le look reste dynamique avec des coloris allant du sobre avec la noire classique au plus punchy\u00a0!<br class=\"none\" \/><br class=\"none\" \/><\/span><\/div>\n<div style=\"text-align: justify;\" align=\"center\"><\/div>\n<div style=\"text-align: justify;\" align=\"center\">\n<p><span style=\"font-size: 14px; color: #000000;\"><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/SC3-CS-4.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" class=\"alignleft  wp-image-1497\" style=\"margin: 5px 10px;\" alt=\"SC3 CS 4\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/SC3-CS-4-300x225.jpg\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/SC3-CS-4-300x225.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/SC3-CS-4.jpg 480w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Bref, me voil\u00e0 chauss\u00e9 de la <strong><strong>SPEED CROSS 3 CS<\/strong> <\/strong>pour arpenter les chemins au Honduras\u00a0! On se sent tout de suite bien dedans et c\u2019est super agr\u00e9able. Attention cependant si vous avez les talons fragiles, car le contrefort est assez rigide sur les trois\/quatre premi\u00e8res s\u00e9ances (pr\u00e9voir les compeeds dans le sac lors de vos premi\u00e8res foul\u00e9es). Mais cette duret\u00e9 disparait tr\u00e8s vite, comme pour la SALOMON S-LAB. <br class=\"none\" \/><br class=\"none\" \/>Un des points remarquable est <strong><strong>l\u2019absence de couture<\/strong> <\/strong>\u00e0 l\u2019int\u00e9rieur du chausson. Aucun frottement donc\u00a0!Notons que le chausson de la <strong>SALOMON SPEED CROSS 3<\/strong>\u00a0est, \u00e0 l\u2019image des chaussons des autres mod\u00e8les, mise \u00e0 part la CROSS MAX, un chaussant assez \u00e9troit notamment au niveau du coup de pied. Donc coups de pieds forts, s\u2019abstenir\u00a0! Pas de probl\u00e8me pour moi \u00e0 ce niveau-l\u00e0, le pied est bien cal\u00e9, le talon l\u00e9g\u00e8rement sur\u00e9lev\u00e9, ce qui donne envie d\u2019aller de suite les essayer\u00a0!<\/span><\/p>\n<\/div>\n<div align=\"center\">\n<div style=\"text-align: justify;\" align=\"center\"><span style=\"font-size: 14px; color: #000000;\">Mon terrain de test est un peu diff\u00e9rent de celui dont j\u2019avais l\u2019habitude sur Paris (Bois de\u00a0Vincennes) puisque depuis septembre, je suis \u00e0 Tegucigalpa au\u00a0Honduras &#8230; le d\u00e9cor ici c\u2019est des for\u00eats aux pieds de montagnes \u00e0 perte de vue entre 1000m et 2000m d\u2019altitude. Les sentiers y sont humides dans les for\u00eats mais aussi secs et rocheux en montagne.<br class=\"none\" \/><br class=\"none\" \/><\/span><\/div>\n<div style=\"text-align: justify;\" align=\"center\"><\/div>\n<div style=\"text-align: justify;\" align=\"center\"><\/div>\n<div align=\"center\"><span style=\"font-size: 14px; color: #000000;\"><span style=\"font-size: 14px; color: #000000;\"><span style=\"font-size: 14px; color: #000000;\"><span style=\"font-size: 14px; color: #000000;\"><span style=\"font-size: 14px; color: #000000;\"><span style=\"font-size: 14px; color: #000000;\"><span style=\"font-size: 14px; color: #000000;\"><span style=\"font-size: 14px; color: #000000;\"><span style=\"font-size: 14px; color: #000000;\"><span style=\"font-size: 14px; color: #000000;\"><span style=\"font-size: 14px; color: #000000;\"><span style=\"font-size: 14px; color: #000000;\"><span style=\"font-size: 14px; color: #000000;\"><span style=\"font-size: 14px; color: #000000;\"><span style=\"font-size: 14px; color: #000000;\"><span style=\"font-size: 14px; color: #000000;\"><span style=\"font-size: 14px; color: #000000;\"><span style=\"font-size: 14px; color: #000000;\"><span style=\"font-size: 14px; color: #000000;\"><span style=\"font-size: 14px; color: #000000;\"><span style=\"font-size: 14px; color: #000000;\"><span style=\"font-size: 14px; color: #000000;\"><span style=\"font-size: 14px; color: #000000;\"><span style=\"font-size: 14px; color: #000000;\"><div id='gallery-2' class='gallery galleryid-1493 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.team-outdoor.fr\/blog\/sc3-cs-5\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/SC3-CS-5-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.team-outdoor.fr\/blog\/sc3-cs-11\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/SC3-CS-11-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.team-outdoor.fr\/blog\/sc3-cs-6\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/SC3-CS-6-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n<\/p>\n<p><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/SC3-CS-7.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"274\" class=\"alignright  wp-image-1500\" style=\"margin: 5px 10px;\" alt=\"SC3 CS 7\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/SC3-CS-7-300x274.jpg\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/SC3-CS-7-300x274.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/SC3-CS-7.jpg 394w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Me voici ainsi, <strong><strong>SALOMON SPEED CROSS 3 CS<\/strong> <\/strong>aux pieds \u00e0 suivre les traces des\u00a0gu\u00e9pards&#8230;( pas de second degr\u00e9 ici\u2026\u00a0;), destination Pico Bonito en face des\u00a0Iles<\/span><br \/>\n<span style=\"font-size: 14px; color: #000000;\"> Cara\u00efbes! Le terrain est ici humide et glissant. C\u2019est donc un terrain de jeu id\u00e9al pour tester mes nouvelles chaussures &#8211; et pour rencontrer des tarentules, mais je suis par\u00e9, avec ma membrane CS qui me prot\u00e8ge de ces b\u00e9b\u00e8tes\u00a0!<\/span><\/p>\n<\/div>\n<div style=\"text-align: justify;\" align=\"center\"><\/div>\n<div style=\"text-align: justify;\" align=\"center\"><span style=\"font-size: 14px; color: #000000;\">Lorsqu\u2019on regarde la semelle ext\u00e9rieure de la SPEED CROSS, les <strong><strong>crampons en forme de chevrons<\/strong> <\/strong>fortement espac\u00e9s laissent envisager une forte accroche sur ce genre de terrain. On attend donc la chaussure au retour\u00a0! \u2026 Et on n\u2019est pas d\u00e9\u00e7u, loin de l\u00e0\u00a0! L\u2019accroche est excellente et la boue se d\u00e9croche de la chaussure entre chaque appui sur le sol boueux. Quel plaisir de courir ainsi et d\u2019enchainer. La chaussure r\u00e9pond et transmet de l\u2019\u00e9nergie \u00e0 chaque relance\u2026\u00a0on se sent voler\u2026 comme Kilian\u2026. Ou presque\u00a0! Le <strong><strong>pare-pierre<\/strong> <\/strong>sur le devant du pied est suffisant et<strong> prot\u00e8ge bien des racines ou roches<\/strong> que l\u2019on peut rencontrer.<br class=\"none\" \/><br class=\"none\" \/><\/span><\/div>\n<div style=\"text-align: center;\" align=\"center\">\n<div id='gallery-3' class='gallery galleryid-1493 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.team-outdoor.fr\/blog\/sc3-cs-10\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/SC3-CS-10-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.team-outdoor.fr\/blog\/sc3-cs-9\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/SC3-CS-9-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.team-outdoor.fr\/blog\/sc3-cs-8\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/SC3-CS-8-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.team-outdoor.fr\/blog\/on-a-teste-pour-vous-la-salomon-speed-cross-3\/sc3-cs-7\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/SC3-CS-7-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<\/div>\n<div style=\"text-align: justify;\" align=\"center\"><\/div>\n<div style=\"text-align: justify;\" align=\"center\"><\/div>\n<p style=\"text-align: justify;\" align=\"center\"><span style=\"font-size: 14px; color: #000000;\"><strong>La membrane CS <\/strong>est franchement une r\u00e9ussite et bien plus int\u00e9ressante qu\u2019une chaussure GORETEX int\u00e9grale. Apr\u00e8s deux heures de balade sur les chemins humides, mes pieds restent secs. M\u00eame r\u00e9sultat que celui obtenu avec une membrane GORETEX, mais le gros avantage est que cette nouvelle membrane CS est beaucoup plus souple\u2026 et autre gros avantage de la membrane CS par rapport \u00e0 une membrane GORETEX\u00a0: m\u00eame au-dessus d\u2019une temp\u00e9rature de 25\u00b0, la transpiration est bien \u00e9vacu\u00e9e\u00a0! Par contre, pour l\u2019\u00e9t\u00e9, je lui pr\u00e9f\u00e8rerais tout de m\u00eame les <strong>SPEED CROSS 3<\/strong> classiques, sans membrane.<\/span><\/p>\n<p style=\"text-align: justify;\" align=\"center\"><span style=\"font-size: 14px; color: #000000;\">J\u2019ai aussi \u00e9prouv\u00e9 mes nouvelles chaussures sur terrains secs et plus durs. Elles ont \u00e9galement un bon rendu en termes de <strong>dynamisme<\/strong>. L\u00e0 encore, aucun probl\u00e8me de surchauffe des pieds. Notons cependant, que <strong><strong>la stabilit\u00e9<\/strong> <\/strong>y est moindre que sur mes SALOMON S-LAB 3. Petit b\u00e9mol cependant sur ce genre de terrains, c\u2019est qu\u2019il use plus rapidement la <strong>gomme assez tendre de la semelle ext\u00e9rieure<\/strong>. On diminue donc sensiblement la dur\u00e9e de vie de la chaussure sur des terrains plus durs.<\/span><\/p>\n<div align=\"center\"><span style=\"color: #ff6600; font-size: 16px;\"><strong><strong><strong><strong><strong><strong><br class=\"none\" \/>Coups de pouce <\/strong>coureur<\/strong><\/strong><\/strong><\/strong><\/strong><\/span><\/div>\n<\/div>\n<div style=\"text-align: justify;\" align=\"center\"><strong><br \/>\n<a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/SC3-CS-12.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" class=\"alignleft  wp-image-1505\" style=\"margin: 5px 10px;\" alt=\"SC3 CS 12\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/SC3-CS-12-300x225.jpg\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/SC3-CS-12-300x225.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/SC3-CS-12.jpg 480w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><span style=\"color: #000000;\">1. Pour assurer le bon serrage de la chaussure<\/span><\/strong><span style=\"color: #000000;\">, une fois le quick-lace serr\u00e9, tourner deux fois autour du tanka (bague plastique serrant les lacets) avant de mettre le tout dans la petite poche en haut de la languette<br class=\"none\" \/><br class=\"none\" \/><\/span><\/div>\n<div style=\"text-align: justify;\" align=\"center\"><\/div>\n<div style=\"text-align: justify;\" align=\"center\"><span style=\"color: #000000;\"><strong>2. En termes d\u2019amorti,<\/strong> ce mod\u00e8le est plus \u00e0 conseiller \u00e0 des gabarits en dessous de 80 kilo si l\u2019on veut que la chaussure dure une saison enti\u00e8re<strong>3. <\/strong>Pour ceux qui ont les doigts de pieds en crochet (qui se rel\u00e8vent vers le haut de la chaussure), \u00e0 noter que l\u2019espace entre les doigts de pieds et le haut de la chaussure est relativement faible\u2026 faire attention qu\u2019il vous reste assez de place si vous remplacez la semelle de propret\u00e9 par une semelle podologique.<br class=\"none\" \/><br class=\"none\" \/><\/span><\/div>\n<div align=\"center\"><\/div>\n<div align=\"center\">\n<div align=\"center\"><span style=\"font-size: 22px; color: #ff6600;\"><strong><br class=\"none\" \/>RECAP TEST<\/strong><\/span><\/div>\n<div align=\"center\"><\/div>\n<div style=\"text-align: justify; padding-left: 240px;\" align=\"center\"><strong><br class=\"none\" \/><span style=\"font-size: 14px; color: #000000;\">Points (+)<\/span><\/strong><\/div>\n<div style=\"text-align: justify;\" align=\"center\"><\/div>\n<div style=\"text-align: justify; padding-left: 240px;\" align=\"center\"><span style=\"font-size: 14px; color: #000000;\">&#8211; le confort<\/span><\/div>\n<div style=\"text-align: justify; padding-left: 240px;\" align=\"center\"><span style=\"font-size: 14px; color: #000000;\">&#8211; l&rsquo;accroche sur terrains mous et boueux<\/span><\/div>\n<div style=\"text-align: justify; padding-left: 240px;\" align=\"center\"><span style=\"font-size: 14px; color: #000000;\">&#8211; le dynamisme et la relance<\/span><\/div>\n<div style=\"text-align: justify; padding-left: 240px;\" align=\"center\"><span style=\"font-size: 14px; color: #000000;\">&#8211; la membrane CS, une vraie r\u00e9volution!<br class=\"none\" \/><br class=\"none\" \/><\/span><\/div>\n<div style=\"text-align: justify;\" align=\"center\"><\/div>\n<div style=\"text-align: justify; padding-left: 240px;\" align=\"center\"><span style=\"color: #000000;\"><strong>Points (-)<\/strong><\/span><\/div>\n<div style=\"text-align: justify; padding-left: 240px;\" align=\"center\"><\/div>\n<div style=\"text-align: justify; padding-left: 240px;\" align=\"center\"><span style=\"color: #000000;\">&#8211; usure sur terrain sec<\/span><\/div>\n<div style=\"text-align: justify; padding-left: 240px;\" align=\"center\"><span style=\"color: #000000;\">&#8211; contrefort talon un peu rigide au d\u00e9part<\/span><\/div>\n<div style=\"text-align: justify; padding-left: 240px;\" align=\"center\"><span style=\"color: #000000;\">&#8211; amorti l\u00e9ger pour des gabarits plus lourds<br class=\"none\" \/><br class=\"none\" \/><\/span><\/div>\n<div style=\"padding-left: 420px;\" align=\"center\"><\/div>\n<div style=\"text-align: justify;\" align=\"center\"><span style=\"font-size: 14px; color: #000000;\"><span style=\"font-size: 16px;\"><strong>Conclusion :<\/strong><\/span> Je conseillerais les SALOMON SPEED CROSS 3 CS pour tous ceux qui vont aller arpenter des chemins boueux \u2013 comme sur l\u2019ICE TRAIL, par exemple \u2013 ou pour les s\u00e9ances rapides sur des terrains souples. Pour les raids (mesh tr\u00e8s r\u00e9sistant et pieds au sec) en sous-bois ou pour les bike &amp; Run boueux o\u00f9 le dynamisme est un mot cl\u00e9<\/span><\/div>\n<div align=\"center\"><\/div>\n<div align=\"center\">\n<div align=\"center\">\n<p align=\"center\"><span style=\"font-size: 16px; color: #ff6600;\"><strong><br class=\"none\" \/><br class=\"none\" \/>La SPEED CROSS 3 pour les filles<\/strong><\/span><\/p>\n<p align=\"center\"><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/SC3-CS-14.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" class=\" wp-image-1507 alignnone\" style=\"margin: 5px 10px;\" alt=\"SC3 CS 14\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/SC3-CS-14-225x300.jpg\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/SC3-CS-14-225x300.jpg 225w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/SC3-CS-14.jpg 270w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/SC3-CS-13.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"163\" class=\" wp-image-1506 alignnone\" style=\"margin: 5px 10px;\" alt=\"SC3 CS 13\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/SC3-CS-13-300x163.jpg\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/SC3-CS-13-300x163.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/04\/SC3-CS-13.jpg 480w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\">Alors mesdames et mesdemoiselles, la couleur de l&rsquo;ann\u00e9e 2012, c&rsquo;est le viloet et la SALOMOn SPEED CROSS 3 ne d\u00e9roge pas \u00e0 la r\u00e8gle&#8230; et pour les plus coquettes, elle s&rsquo;accorde parfaitement avec la veste imperm\u00e9able \u00e0 capuche XT WP jacket,\u00a0label UTMB et autres ultras.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>par Thierry QUICROIT, conseiller vente Team Outdoor, juillet &#8211; Aout 2011 Apr\u00e8s ma premi\u00e8re r\u00e9elle saison trail et avoir us\u00e9 mes SALOMON S-LAB 3 et\u00a0mes BROOKS CASCADIA 6 jusqu&rsquo;\u00e0 la disparition de tous les crampons, je me\u00a0suis d\u00e9cid\u00e9 \u00e0 passer sur les SALOMON SPEED CROSS 3 CS. Pour ceux qui connaissent les deux versions\u00a0pr\u00e9c\u00e9dentes, de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1510,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1493","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-on-a-teste-pour-vous","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"_links":{"self":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts\/1493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/comments?post=1493"}],"version-history":[{"count":30,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts\/1493\/revisions"}],"predecessor-version":[{"id":1513,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts\/1493\/revisions\/1513"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/media\/1510"}],"wp:attachment":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/media?parent=1493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/categories?post=1493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/tags?post=1493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}