{"id":3586,"date":"2013-10-31T10:39:39","date_gmt":"2013-10-31T09:39:39","guid":{"rendered":"http:\/\/www.team-outdoor.fr\/blog\/?p=3586"},"modified":"2013-10-31T10:40:09","modified_gmt":"2013-10-31T09:40:09","slug":"au-top-au-marathon-des-villages","status":"publish","type":"post","link":"https:\/\/www.team-outdoor.fr\/blog\/au-top-au-marathon-des-villages\/","title":{"rendered":"Au TOP au marathon des Villages!"},"content":{"rendered":"<p style=\"text-align: center;\"><span style=\"color: #ff6600;\"><strong><span style=\"font-size: 20px;\">par Guillaume VIMENEY &#8211; SALOMON &#8211; Team Outdoor Paris<\/span><\/strong><\/span><\/p>\n<p align=\"center\"><span style=\"font-size: 20px;\"><span style=\"font-size: 18px;\"><br class=\"none\" \/><br class=\"none\" \/><span style=\"color: #000000;\"><strong>MARATHON DES VILLAGES (33) \u2013 42,195 KMS &#8211;\u00a0 13 octobre 2013<\/strong><\/span><\/span><b><br \/>\n<\/b><\/span><\/p>\n<p style=\"text-align: center;\" align=\"center\"><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/lege-cap-ferret0.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-3575\" alt=\"lege-cap-ferret0\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/lege-cap-ferret0.jpg\" width=\"634\" height=\"328\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/lege-cap-ferret0.jpg 792w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/lege-cap-ferret0-300x155.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/lege-cap-ferret0-600x310.jpg 600w\" sizes=\"auto, (max-width: 634px) 100vw, 634px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong><br class=\"none\" \/><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/DSCN4554.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-3574\" style=\"margin: 5px 10px;\" alt=\"DSCN4554\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/DSCN4554.jpg\" width=\"235\" height=\"314\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/DSCN4554.jpg 480w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/DSCN4554-225x300.jpg 225w\" sizes=\"auto, (max-width: 235px) 100vw, 235px\" \/><\/a>Depuis le mois de juin, je me suis accord\u00e9 un bon cong\u00e9 paternit\u00e9<\/strong>, o\u00f9 j\u2019ai pleinement pu m\u2019occuper et surtout profiter de la derni\u00e8re recrue de la famille, Eimi. En trois mois, j\u2019ai d\u00fb r\u00e9aliser une petite dizaine de footings seulement. J\u2019ai donc fait l\u2019impasse sur le Grand Raid des Pyr\u00e9n\u00e9es (160km) qui \u00e9tait pourtant au programme.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong>D\u00e9but septembre, j\u2019ai repris le chemin de l\u2019entra\u00eenemen<\/strong>t, avec beaucoup de joie et d\u2019envie. Plus exigeant envers moi-m\u00eame, j\u2019ai chang\u00e9 pas mal de choses \u00e0 ma pr\u00e9paration physique. J\u2019axe davantage mon travail sur la puissance, avec notamment du v\u00e9lo et du renforcement musculaire. Au niveau di\u00e9t\u00e9tique, j\u2019ai succomb\u00e9 au r\u00e9gime sans gluten, tr\u00e8s en vogue en ce moment. Je ne mange donc plus de bl\u00e9 et ses d\u00e9riv\u00e9s (c\u00e9r\u00e9ales, pain, p\u00e2tes, farine, biscuits, croissants\u2026). Les premiers jours ont \u00e9t\u00e9 difficiles. Aujourd\u2019hui, je suis convaincu par l\u2019efficacit\u00e9 de cette di\u00e9t\u00e9tique, qui n\u2019est pas \u00e9trang\u00e8re \u00e0 mon excellente forme.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong>Malgr\u00e9 tout, les nombreuses semaines d\u2019inactivit\u00e9 se sont fait sentir<\/strong>. Remettre la machine en route a pris un certain temps. Quinze jours avant le marathon, j\u2019ai r\u00e9alis\u00e9 un premier test, sur le Trail des Coteaux, avec une victoire \u00e0 la clef. Cela m\u2019a donn\u00e9 confiance et m\u2019a confort\u00e9 dans mes choix de pr\u00e9paration.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/marathon-L\u00e8ge-cap-Ferret-2013-2.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-3578\" style=\"margin: 5px 10px;\" alt=\"marathon L\u00e8ge cap Ferret 2013 (2)\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/marathon-L\u00e8ge-cap-Ferret-2013-2-300x225.jpg\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/marathon-L\u00e8ge-cap-Ferret-2013-2-300x225.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/marathon-L\u00e8ge-cap-Ferret-2013-2-1024x768.jpg 1024w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/marathon-L\u00e8ge-cap-Ferret-2013-2-600x450.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Avec un petit mois d\u2019entra\u00eenement, je ne m\u2019attends pas \u00e0 sortir un chrono exceptionnel<\/strong>, d\u2019autant plus que le parcours est loin d\u2019\u00eatre roulant. Toutefois, l\u2019objectif demeure de remporter le marathon. Je ne connais pas le trac\u00e9, mais mon p\u00e8re, qui a d\u00e9j\u00e0 particip\u00e9 \u00e0 cet \u00e9v\u00e8nement, m\u2019a donn\u00e9 de bons conseils. Reste quelques appr\u00e9hensions vis-\u00e0-vis de mon pied droit douloureux, malgr\u00e9 les soins qui lui ont \u00e9t\u00e9 prodigu\u00e9s. Nonobstant, j\u2019esp\u00e8re y penser le moins possible au cours des 42km.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong>Situ\u00e9e sur la presqu\u2019\u00eele du Cap Ferret, la course s\u2019annonce grandiose.<\/strong> J\u2019adore cet environnement et ce cadre de vie, qui se pr\u00eatent tellement au plaisir de courir. Il y a deux ans, je me rappelle avoir remport\u00e9 l\u2019\u00e9tape longue de la Trans Aq\u2019 sur ces terres. Un merveilleux souvenir. D\u2019ailleurs, nous arpenterons ce dimanche certains passages qui devraient se rappeler \u00e0 ma m\u00e9moire. En tout cas, j\u2019aime cet air marin, ce climat oc\u00e9anique, ces for\u00eats de pins, ces plages de sable fin, ces dunes de sables\u2026<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong>Arriv\u00e9 en famille sur les lieux une bonne heure avant le d\u00e9part,<\/strong> j\u2019ai le loisir de m\u2019\u00e9chauffer sereinement et de monter en puissance progressivement. Je ressens quelques g\u00eanes au niveau du pied, mais la forme est bien pr\u00e9sente. Je me sens l\u00e9ger. J\u2019ai h\u00e2te\u00a0!!! Epingler \u00e0 nouveau un dossard sur un objectif me ravi. Je n\u2019ai que des pens\u00e9es positives en t\u00eate. Suite \u00e0 mon \u00e9chauffement, je me place sur la ligne quelques instants avant le d\u00e9part. Je n\u2019ai pas le temps de tergiverser, de me poser des questions, simplement le temps d\u2019embrasser mes proches.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/marathon-des-villages-611.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-3580\" style=\"margin: 5px 10px;\" alt=\"marathon-des-villages-611\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/marathon-des-villages-611-300x200.jpg\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/marathon-des-villages-611-300x200.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/marathon-des-villages-611-600x400.jpg 600w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/marathon-des-villages-611.jpg 700w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>A 9h30 pr\u00e9cises, le coup de pistolet retentit sur la presqu\u2019\u00eele<\/strong> et les quelques 1400 coureurs s\u2019engagent sur la distance olympique. Les premi\u00e8res foul\u00e9es permettent de jauger les forces en pr\u00e9sence. D\u00e8s le pr\u00e9ambule de la bataille, je me place en premi\u00e8re ligne.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong>A mes c\u00f4t\u00e9s, j\u2019aper\u00e7ois Patrice Bruel, Manuel Ferreira et Fr\u00e9d\u00e9ric Lastisn\u00e8res<\/strong> entre autres. La course d\u00e9bute par une petite boucle en ville avec des virages assez secs \u00e0 n\u00e9gocier.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong>Trouvant le rythme peu soutenu, je d\u00e9cide d\u2019acc\u00e9l\u00e9rer le train.<\/strong> Egalement offensif, Manuel Ferreira se positionne pr\u00e8s de moi. Assez vite, nous allons prendre une bonne centaine de m\u00e8tres sur nos poursuivants. D\u00e9sormais pour le moins \u00e9lev\u00e9e, l\u2019allure me convient parfaitement. Avec Manuel,\u00a0on se relaie de temps \u00e0 autres. Apr\u00e8s 5 kms, nous prenons une piste cyclable qui s\u2019enfonce dans les pins. Adorant ce type de passage,\u00a0je d\u00e9cide de prendre les choses en main. Manuel Ferreira se situe tout juste derri\u00e8re. Toujours vallonn\u00e9e, la route laisse peu de r\u00e9pit aux marathoniens, qui doivent composer avec les incessantes mont\u00e9es et descentes qui s\u2019affichent devant eux. Peu apr\u00e8s,\u00a0nous gagnons la plage ou un tapis a gentiment \u00e9t\u00e9 d\u00e9pos\u00e9 par les organisateurs, afin d\u2019\u00e9viter de rentrer en contact avec le sable. Le passage n\u2019est pas ais\u00e9 et peut facilement d\u00e9traquer le d\u00e9roulement ordinaire de sa foul\u00e9e. Au sortir de cette difficult\u00e9, je relance l\u2019allure. Nous traversons alors le joli village ostr\u00e9icole de Piquey.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/marathon-des-villages-7-2.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-3576\" style=\"margin: 5px 10px;\" alt=\"marathon des villages le vainqueur\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/marathon-des-villages-7-2-162x300.jpg\" width=\"162\" height=\"300\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/marathon-des-villages-7-2-162x300.jpg 162w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/marathon-des-villages-7-2-553x1024.jpg 553w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/marathon-des-villages-7-2-600x1109.jpg 600w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/marathon-des-villages-7-2.jpg 1604w\" sizes=\"auto, (max-width: 162px) 100vw, 162px\" \/><\/a>Durant ce d\u00e9but de course, je me pose de nombreuses questions<\/strong>. Inquiet par la vitesse \u00e0 laquelle d\u00e9filent les kilom\u00e8tres, je m\u2019interroge sur ma capacit\u00e9 \u00e0 maintenir la cadence jusqu\u2019au bout. N\u2019est-on pas parti trop pr\u00e9cipitamment\u00a0? Ma pr\u00e9paration pour le marathon ayant \u00e9t\u00e9 tr\u00e8s raccourcie, j\u2019ignore comment mes jambes vont dig\u00e9rer ce type d\u2019effort. De plus, sur le bitume, j\u2019ai moins de rep\u00e8res que sur les sentiers. Je me questionne sur les cons\u00e9quences des chocs sur les mollets et les quadriceps. Toutefois, loin d\u2019\u00eatre asphyxi\u00e9, je m\u2019oxyg\u00e8ne confortablement. Apr\u00e8s 10 kilom\u00e8tres, les voyants sont dans le vert. Derri\u00e8re, les poursuivants semblent peiner, mais Manuel s\u2019accroche. Au 11<sup>e\u00a0<\/sup>km, je profite de la c\u00f4te de la Pointe aux Chevaux longue de 400m pour m\u2019\u00e9chapper. J\u2019acc\u00e9l\u00e8re en essayant de d\u00e9cramponner mon sympathique adversaire du jour. Avec une vingtaine de m\u00e8tres d\u2019avance, loin de crier victoire, je sais que je dois pers\u00e9v\u00e9rer et continuer \u00e0 attaquer.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong>Par la suite, nous repassons dans le centre-ville de L\u00e8ge-Cap Ferret<\/strong> (15<sup>e<\/sup>\u00a0km). Mon p\u00e8re en profite pour me passer une bouteille et un gel, que je saisis \u00e0 la vol\u00e9e. Dans la foule, j\u2019entends un \u00ab\u00a0fighting spirit\u00a0\u00bb qui se distingue des applaudissements. Valessa est aux premi\u00e8res loges pour nous voir filer. Manuel pointe \u00e0 une dizaine de secondes apr\u00e8s mon passage. Rien n\u2019\u2019est jou\u00e9\u00a0!<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong>Dans ce type de situation, je demeure fid\u00e8le \u00e0 une r\u00e8gle de conduite<\/strong>\u00a0: je ne me retourne jamais. Je me concentre seulement sur mes sensations. Surtout, j\u2019\u00e9vite d\u2019envoyer des signaux n\u00e9gatifs \u00e0 mes poursuivants, en laissant penser que je faiblis. Le regard et les pens\u00e9es se portent toujours loin devant. Seules m\u2019int\u00e9ressent les prochaines foul\u00e9es qui me rapprochent in\u00e9luctablement du but.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong>J<a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/113.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-3589\" style=\"margin: 5px 10px;\" alt=\"11\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/113-219x300.jpg\" width=\"219\" height=\"300\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/113-219x300.jpg 219w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/113.jpg 249w\" sizes=\"auto, (max-width: 219px) 100vw, 219px\" \/><\/a>\u2019en profite donc pour m\u2019hydrater et prendre quelques forces.<\/strong> Les prochains kilom\u00e8tres seront d\u00e9terminants sur l\u2019issue du marathon. Nous arpentons \u00e0 nouveau la piste cyclable et son profil accident\u00e9, pour prendre la direction de la pointe de la presqu\u2019\u00eele. Il se met alors \u00e0 pleuvoir. Imperturbable, j\u2019y songe \u00e0 peine et me focalise sur l\u2019effort. Au 20<sup>e<\/sup>\u00a0km, une grande route d\u00e9partementale se substitue au charme des pr\u00e9c\u00e9dents chemins. A ce moment, il ne faut surtout pas rel\u00e2cher son effort. Mon p\u00e8re m\u2019attend alors et va m\u2019accompagner en v\u00e9lo une centaine de m\u00e8tres devant, afin de m\u2019ouvrir la voie. Voil\u00e0 une chose tr\u00e8s rassurante et motivante pour moi\u00a0!<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong>Au 24<sup>e<\/sup>\u00a0km, le trac\u00e9 jouxte le phare, d\u2019un rouge flamboyant et si reconnaissable,<\/strong> de L\u00e8ge Cap Ferret. Une belle image, qui nous rappelle de ne pas se perdre sur le chemin. Plus que jamais, il faut rester concentr\u00e9 et vigilent. Il ne faut pas s\u2019enflammer. Le 30<sup>e<\/sup>\u00a0km sera seul juge pour d\u00e9signer ceux qui se seront montr\u00e9s intr\u00e9pides. Quelques kilom\u00e8tres plus loin, je perds justement le cap, en m\u2019\u00e9garant sur le parcours. Parvenu \u00e0 La Pointe, on m\u2019indique de prendre \u00e0 gauche. Je prends donc la route qui s\u2019ouvre \u00e0 moi. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong>Malheureusement, il fallait faire demi-tour\u2026<\/strong> Je dois rapidement revenir sur mes pas et continuer la marche en avant. Sur ce cafouillage qui m\u2019est enti\u00e8rement imputable, je perds 30 bonnes secondes. Je vois donc Manuel Ferreira et Fr\u00e9d\u00e9ric Lastisn\u00e8res revenir dans mon sillage. Nous en sommes alors au 28<sup>e<\/sup>\u00a0km. D\u00e9sormais, situ\u00e9 en ligne de mire de mes concurrents, il va falloir \u00eatre fort sur la fin de parcours et surtout ne plus penser \u00e0 cette m\u00e9saventure. J\u2019ext\u00e9riorise ma frustration un bon coup, avant de repartir \u00e0 l\u2019attaque. Au 30<sup>e<\/sup>\u00a0km, je constate que tout va pour le mieux. Les muscles ne sont pas raides, la glyc\u00e9mie est fixe, je suis lucide et d\u00e9termin\u00e9. Je sens que j\u2019ai une marge. S\u2019il m\u2019arrive d\u2019\u00eatre rejoint, je pourrai le cas \u00e9ch\u00e9ant acc\u00e9l\u00e9rer. Je n\u2019ai pas encore puis\u00e9 dans mes ressources psychiques.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/P1110362.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-3582\" style=\"margin: 5px 10px;\" alt=\"P1110362\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/P1110362-216x300.jpg\" width=\"216\" height=\"300\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/P1110362-216x300.jpg 216w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/P1110362.jpg 511w\" sizes=\"auto, (max-width: 216px) 100vw, 216px\" \/><\/a>Le village ostr\u00e9icole du Cap Ferret s\u2019offre alors \u00e0 nous. Superbe\u00a0!!<\/strong> Les virages sont secs, les relances nombreuses, mais le d\u00e9tour vaut le coup d\u2019\u0153il. Nous prenons alors des sentiers boueux et sinueux, peu habituel pour un marathon. Au 33<sup>e<\/sup>\u00a0km, une piste cyclable longue de 5 km, est cens\u00e9e nous amener jusqu\u2019\u00e0 la derni\u00e8re difficult\u00e9 de la journ\u00e9e. A cet instant, j\u2019ai conscience que la victoire me tend les bras. Je me sens l\u00e9ger, m\u00eame si les quadriceps se sont durcis. Cependant, j\u2019ai de bonnes jambes. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong>Au 38<sup>e<\/sup>\u00a0km, le village ostr\u00e9icole de l\u2019Herbe nous accueille<\/strong>. Comme dans chaque travers\u00e9e de village, la foule est nombreuse pour nous pousser et accompagner notre effort. Puis vient, une mont\u00e9e abrupte d\u2019une centaine de m\u00e8tres et compos\u00e9e d\u2019une quarantaine de marches. Ce n\u2019est pas le moment de flancher. J\u2019essaie de mettre du rythme pour grimper en maintenant une bonne allure. Arriv\u00e9 en haut des escaliers, je constate qu\u2019il n\u2019y a personne en contre-bas. Sur le bord de la route, les spectateurs me confirment mon impression. Je peux entendre des mots de soutien qui me rassurent bien\u00a0: \u00ab\u00a0<em>C\u2019est bon. C\u2019est gagn\u00e9\u00a0!!<\/em>\u00a0\u00bb, \u00ab\u00a0<em>Tu es seul. Il n\u2019y a personne\u00a0<\/em>\u00bb\u2026 Il reste encore \u00e0 monter une bonne butte avant de n\u00e9gocier la descente. 3 km me s\u00e9parent encore de l\u2019arriv\u00e9e. Sur la fin du parcours, je savoure\u00a0: \u00ab\u00a0Je l\u2019ai fait\u00a0!!\u00a0\u00bb. Je me rapproche confortablement des 42km, sans durcir le rythme. Nous visitons alors le village ostr\u00e9icole de Piraillon, dont la beaut\u00e9 nous fait subitement oublier toutes nos afflictions. \u00a0L\u2019organisateur David Le Goff m\u2019accompagne en v\u00e9lo sur ces instants magiques.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/102.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-3588\" style=\"margin: 5px 10px;\" alt=\"10\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/102-300x185.jpg\" width=\"300\" height=\"185\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/102-300x185.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/102.jpg 559w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Je boucle le marathon en 2h37 et surtout \u00e0 la 1<sup>e<\/sup>\u00a0place.<\/strong> L\u2019objectif est rempli. Je partage cette joie avec ma famille. La pr\u00e9sence de mon p\u00e8re, qui m\u2019aura accompagn\u00e9 en v\u00e9lo sur le second semi-marathon, m\u2019aura \u00e9t\u00e9 tr\u00e8s profitable. Merci\u00a0!!! Bien qu\u2019\u00e9court\u00e9e, la pr\u00e9paration aura finalement \u00e9t\u00e9 suffisante pour l\u2019emporter. Quatre minutes plus tard, c\u2019est Fr\u00e9d\u00e9ric Lastisn\u00e8res qui s\u2019empare brillamment de la seconde place. Plus loin, Patrice Bruel compl\u00e8te une nouvelle fois le podium.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong>Cette victoire est \u00e9galement synonyme de d\u00e9part dans les Cara\u00efbes<\/strong> d\u00e9but d\u00e9cembre pour participer \u00e0 la Trans Martinique (135km). Ce sera la derni\u00e8re course de l\u2019ann\u00e9e, et cette fois je ne crains pas l\u2019hypothermie qui m\u2019avait paralys\u00e9e l\u2019an dernier \u00e0 la Saint\u00e9Lyon.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/P1110414.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-3583\" style=\"margin: 5px 10px;\" alt=\"P1110414\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/P1110414-300x225.jpg\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/P1110414-300x225.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/P1110414.jpg 401w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>D\u2019ann\u00e9e en ann\u00e9e, le marathon des villages s\u2019inscrit comme un des plus beaux rendez-vous sur la distance en hexagone<\/strong>. Le trac\u00e9 arpente les plus beaux endroits de la presqu\u2019\u00eele. Les coureurs peuvent se r\u00e9galer du Centre Equestre, des villages ostr\u00e9icoles, du phare, des plages et des supporters en nombre sur le bord des routes. Pour cette 7<sup>e<\/sup>\u00a0\u00e9dition, l\u2019organisation \u00e9tait parfaitement rod\u00e9e. L\u2019ambiance festive et conviviale de la course vous fera oublier tous les grands marathons autant m\u00e9diatis\u00e9s qu\u2019aseptis\u00e9s. Sur une \u00e9preuve, o\u00f9 l\u2019on peut craindre de se retrouver seul, retranch\u00e9 dans un effort si solitaire, vous serez accompagn\u00e9 durant toute votre aventure, par les odeurs d\u2019iode et de pins, ainsi que la joie de vivre des participants, qui ne rechignent pas \u00e0 se d\u00e9guiser pour rappeler que nous sommes l\u00e0 avant tout pour nous amuser et prendre du bon temps. \u00a0Pour ma part, dans mon calendrier, la date du 12 octobre 2014 est d\u00e9j\u00e0 coch\u00e9e pour profiter \u00e0 nouveau de l\u2019atmosph\u00e8re de ce marathon, extraordinaire par bien des aspects. Et vous\u00a0? Quel marathon ferez-vous \u00e0 l\u2019automne prochain\u00a0?\u00a0\u00a0 <br class=\"none\" \/><br class=\"none\" \/><\/span><\/p>\n<div id='gallery-1' class='gallery galleryid-3586 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.team-outdoor.fr\/blog\/p1110426\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/P1110426-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.team-outdoor.fr\/blog\/p1110417\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/p1110417-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.team-outdoor.fr\/blog\/marathon-des-villages-1-er-homme\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/marathon-des-villages-28-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.team-outdoor.fr\/blog\/8-4\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/82-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p style=\"text-align: center;\"><span style=\"font-size: 22px;\"><strong><br class=\"none\" \/>Guillaume<br class=\"none\" \/><br class=\"none\" \/><\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/1382344_620563591316020_1360647773_n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3571\" alt=\"1382344_620563591316020_1360647773_n\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/1382344_620563591316020_1360647773_n.jpg\" width=\"720\" height=\"678\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/1382344_620563591316020_1360647773_n.jpg 720w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/1382344_620563591316020_1360647773_n-300x282.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/10\/1382344_620563591316020_1360647773_n-600x565.jpg 600w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>par Guillaume VIMENEY &#8211; SALOMON &#8211; Team Outdoor Paris MARATHON DES VILLAGES (33) \u2013 42,195 KMS &#8211;\u00a0 13 octobre 2013 Depuis le mois de juin, je me suis accord\u00e9 un bon cong\u00e9 paternit\u00e9, o\u00f9 j\u2019ai pleinement pu m\u2019occuper et surtout profiter de la derni\u00e8re recrue de la famille, Eimi. En trois mois, j\u2019ai d\u00fb r\u00e9aliser [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3577,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-3586","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-on-l-a-fait","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"_links":{"self":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts\/3586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/comments?post=3586"}],"version-history":[{"count":5,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts\/3586\/revisions"}],"predecessor-version":[{"id":3593,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts\/3586\/revisions\/3593"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/media\/3577"}],"wp:attachment":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/media?parent=3586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/categories?post=3586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/tags?post=3586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}