{"id":3998,"date":"2013-12-19T10:46:19","date_gmt":"2013-12-19T09:46:19","guid":{"rendered":"http:\/\/www.team-outdoor.fr\/blog\/?p=3998"},"modified":"2013-12-19T11:03:59","modified_gmt":"2013-12-19T10:03:59","slug":"le-cross-de-la-vilette-amnesty-international","status":"publish","type":"post","link":"https:\/\/www.team-outdoor.fr\/blog\/le-cross-de-la-vilette-amnesty-international\/","title":{"rendered":"Le Cross de la Vilette, Amnesty International"},"content":{"rendered":"<p style=\"text-align: center;\"><span style=\"color: #ff6600;\"><strong><span style=\"font-size: 18px;\">Dimanche 17 novembre, Paris 19\u00e8me<\/span><\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><strong><span style=\"font-size: 18px;\">par David MATHIEU et Anne MATHIEU, Team Outdoor Paris<br class=\"none\" \/><br class=\"none\" \/><br class=\"none\" \/><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/Cross-La-Villette-122.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-3993\" alt=\"Cross La Villette 122\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/Cross-La-Villette-122-1024x680.jpg\" width=\"717\" height=\"476\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/Cross-La-Villette-122-1024x680.jpg 1024w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/Cross-La-Villette-122-300x199.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/Cross-La-Villette-122-600x398.jpg 600w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/Cross-La-Villette-122.jpg 1062w\" sizes=\"auto, (max-width: 717px) 100vw, 717px\" \/><\/a><\/span><\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 16px;\"><strong><span style=\"color: #000000;\"><br class=\"none\" \/><br class=\"none\" \/>-EPISODE 1-<\/span><\/strong><\/span><br class=\"none\" \/><br \/>\n<a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/image21.jpeg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-4006\" style=\"margin-left: 10px; margin-right: 10px;\" alt=\"image[2]\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/image21-199x300.jpeg\" width=\"199\" height=\"300\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/image21-199x300.jpeg 199w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/image21.jpeg 556w\" sizes=\"auto, (max-width: 199px) 100vw, 199px\" \/><\/a><span style=\"font-size: 14px; color: #000000;\"><strong>DAVID<\/strong> :<\/span> <span style=\"font-size: 14px; color: #000000;\">J&rsquo;aime retourner courir chaque automne le cross d&rsquo;Amnesty International dans le dix-neuvi\u00e8me arrondissement. Il y a plusieurs raisons \u00e0 \u00e7a: D&rsquo;abord c&rsquo;est une course sympathique, sans pr\u00e9tention; une course de village, de quartier, m\u00eame si ce quartier repr\u00e9sente la sixi\u00e8me ville de France, devant Lille et Bordeaux. C&rsquo;est une courte distance; 8km \u00e7a va vite et \u00e7a me change des \u00e9preuves interminables auxquelles je participe souvent. Je serai au moins finisher et dans un bien meilleur \u00e9tat que si j&rsquo;avais d\u00fb faire 80km en montagne. C&rsquo;est une course \u00e0 domicile, sur mon terrain d&rsquo;entrainement, dans le parc des Buttes Chaumont. Je suis le taulier du parcours et je ne voudrais pas qu&rsquo;on y courre sans moi. et puis courir pour Amnesty, c&rsquo;est aussi l&rsquo;occasion de donner quelques euros et sa signature pour signifier que les droits de l&rsquo;Homme ont un sens et qu&rsquo;on voudrait que cesse l&rsquo;oppression des hommes et des femmes partout o\u00f9 elle s&rsquo;exerce.<\/span><\/p>\n<p><span style=\"font-size: 14px; color: #000000;\"><strong>ANNE<\/strong> : je me m\u00e9fie des courses sur lesquelles David veut m&#8217;emmener courir, elles sont trop longues, trop loin, trop t\u00f4t ou trop ch\u00e8res.<\/span> <span style=\"font-size: 14px; color: #000000;\">Cette course l\u00e0 rentrait dans toute les cases, nous n&rsquo;avions aucun engagement la veille et les inscriptions se faisaient sur place le jour de la course, je me suis laiss\u00e9e convaincre.<br class=\"none\" \/><br class=\"none\" \/><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 16px;\"><strong><span style=\"color: #000000;\">&#8211; EPISODE 2 &#8211;<\/span><\/strong><\/span><br class=\"none\" \/><br \/>\n<strong><span style=\"font-size: 14px; color: #000000;\">DAVID :<\/span><\/strong> <span style=\"font-size: 14px; color: #000000;\">Il fait un froid de canard ce matin mais en courant de la maison \u00e0 la Villette \u00e7a me laisse 4km pour m&rsquo;\u00e9chauffer. Cette ann\u00e9e la course n&rsquo;a pas lieu dans les Buttes Chaumont. Avec les travaux qu&rsquo;il y a dans le parc cette ann\u00e9e, les barri\u00e8res et les tranch\u00e9es, le cross eut \u00e9t\u00e9 transform\u00e9 en steeple chase. La Villette donc; c&rsquo;est aussi \u00ab\u00a0chez moi\u00a0\u00bb mais \u00e7a manque de c\u00f4te. Courir \u00e0 fond sur du plat comme sur une piste d&rsquo;athl\u00e9tisme ce n&rsquo;est pas vraiment ma sp\u00e9cialit\u00e9. J&rsquo;aime bien quand \u00e7a grimpe et que \u00e7a casse les pattes des trop bons coureurs; \u00e7a me laisse un peu de chance. Pour le coup, c&rsquo;est fichu.<\/span> <span style=\"font-size: 14px; color: #000000;\">Les quatre kilom\u00e8tres d&rsquo;\u00e9chauffement sont \u00e0 peine suffisants, j&rsquo;ai encore les muscles froids quand nous atteignons le parc. Ma s\u0153ur nous attend devant la cit\u00e9 de la musique. J&rsquo;ai r\u00e9ussi \u00e0 la convaincre de s&rsquo;inscrire sur sa premi\u00e8re course.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong>ANNE :<\/strong> j&rsquo;accepte de suivre David pour un \u00e9chauffement presqu&rsquo;aussi long que la course. L\u00e0; cela ne sert \u00e0 rien. Le temps de s&rsquo;inscrire et d&rsquo;attendre le d\u00e9part on se sera refroidi. C&rsquo;est un peu ridicule de partir aussi t\u00f4t pour une course dont le d\u00e9part est pr\u00e9vu \u00e0 10h00 mais tant pis. De toute fa\u00e7on, on ira toujours plus vite en trottinant qu&rsquo;en prenant les transports en commun. Il fait froid, j&rsquo;ai enfil\u00e9 trois couches successives, un bonnet rose odlo et des gants.<\/span> <span style=\"font-size: 14px; color: #000000;\">On atteint la Villette \u00e0 9:20, il nous reste quarante minutes pour mourir de froid.<br class=\"none\" \/><\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-size: 14px; color: #000000;\">&#8211; EPISODE 3 &#8211;<\/span><\/strong><br class=\"none\" \/><br \/>\n<a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/image11.jpeg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-4005\" style=\"margin-left: 10px; margin-right: 10px;\" alt=\"image[1]\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/image11-300x199.jpeg\" width=\"300\" height=\"199\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/image11-300x199.jpeg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/image11-1024x681.jpeg 1024w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/image11-600x399.jpeg 600w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/image11.jpeg 1069w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><strong><span style=\"font-size: 14px; color: #000000;\">DAVID :<\/span><\/strong> <span style=\"font-size: 14px; color: #000000;\">L&rsquo;organisation est r\u00e9duite \u00e0 sa plus simple expression. j&rsquo;adore \u00e7a : deux tables, un ordinateur portable pour enregistrer les noms, des dossards et des \u00e9pingles \u00e0 nourrices et c&rsquo;est parti,<\/span> <span style=\"font-size: 14px; color: #000000;\">Nous ne sommes qu&rsquo;une soixantaine. Il y avait les ann\u00e9es pr\u00e9c\u00e9dentes un peu plus de monde. Je ne sais pas si c&rsquo;est le froid ou la d\u00e9localisation qui ont refroidi leurs ardeurs mais ceux qui sont l\u00e0 sont sans doute les plus motiv\u00e9s.<\/span> <span style=\"font-size: 14px; color: #000000;\">Je r\u00e9cup\u00e8re le dossard num\u00e9ro 6. Ce n&rsquo;est pas sur l&rsquo;UTMB que j&rsquo;aurais couru avec un chiffre pareil sur le dos. Il en faut peu pour me mettre la pression.<\/span><br class=\"none\" \/><br \/>\n<span style=\"font-size: 14px; color: #000000;\">Parmi les gars qui s&rsquo;\u00e9chauffent autour de la ligne de d\u00e9part, certains me semblent affut\u00e9s. L&rsquo;un d&rsquo;eux porte un dossard jaune; il ne courra pas le 8km mais le 4km; \u00e7a m&rsquo;arrange bien, vu la vitesse de ses acc\u00e9l\u00e9rations j&rsquo;aurai dans doute du mal \u00e0 le suivre.<\/span> <span style=\"font-size: 14px; color: #000000;\">J&rsquo;effectue encore quelques allers-retours moins pour m&rsquo;\u00e9chauffer que pour le r\u00e9chauffer. On ne tient pas longtemps quand on attend en t-shirt par 2 ou 3 degr\u00e9s.<\/span><br \/>\n<span style=\"font-size: 14px; color: #000000;\">Anne est \u00e9quip\u00e9e comme pour un Trail blanc, elle ne risque pas de prendre froid; d&rsquo;ailleurs, comme elle est bien au chaud, elle ne s&rsquo;\u00e9chauffe pas.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong>ANNE :<\/strong> quelques coureurs sont agglutin\u00e9s autour d&rsquo;une table et de deux chaises. En moins de trois minutes nous sommes inscrits et le dossard \u00e9pingl\u00e9 sur le ventre. Le certificat m\u00e9dical que j&rsquo;ai d\u00fb aller chercher de toute urgence chez notre m\u00e9decin ne sert \u00e0 rien, ils ne le v\u00e9rifient m\u00eame pas.<\/span><br \/>\n<span style=\"font-size: 14px; color: #000000;\">J&rsquo;ai toujours aussi froid et j&rsquo;attends le moment du d\u00e9part pour \u00f4ter mon coupe vent et laisser mon sac \u00ab\u00a0coureur\u00a0\u00bb \u00e0 l&rsquo;abri du buffet. Je veux me servir un verre de th\u00e9 bien chaud mais on m&rsquo;arr\u00eate; les boissons sont r\u00e9serv\u00e9es pour l&rsquo;arriv\u00e9e.<\/span><br class=\"none\" \/><br class=\"none\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 16px;\"><strong><span style=\"color: #000000;\">&#8211; EPISODE 4 &#8211;<\/span><\/strong><\/span><br class=\"none\" \/><br \/>\n<a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/image31.jpeg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-4007\" style=\"margin-left: 10px; margin-right: 10px;\" alt=\"image[3]\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/image31-199x300.jpeg\" width=\"199\" height=\"300\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/image31-199x300.jpeg 199w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/image31.jpeg 588w\" sizes=\"auto, (max-width: 199px) 100vw, 199px\" \/><\/a><span style=\"font-size: 14px; color: #000000;\"><strong>DAVID<\/strong> : on se regroupe sur la ligne. La speaker annonce, avec son m\u00e9gaphone qu&rsquo;elle peine \u00e0 faire fonctionner, les missions sur lesquelles la section locale d&rsquo;Amnesty est engag\u00e9e : la lib\u00e9ration du Dr Tung, un opposant birman, la condition des femmes et les exactions contre les coptes en \u00c9gypte.<\/span> <span style=\"font-size: 14px; color: #000000;\">Ils ont plac\u00e9 les enfants qui courent le 4km devant, pour \u00e9viter les bousculades. Ce n&rsquo;est pas vraiment une bonne id\u00e9e si tout le monde doit partir en m\u00eame temps. Mais \u00e7a fait parti du c\u00f4t\u00e9 sympathique de la course ces sas invers\u00e9s : \u00e9viter de pi\u00e9tiner les enfants au d\u00e9part, \u00e7a contraint de ne pas partir comme une bombe.<\/span> <span style=\"font-size: 14px; color: #000000;\">Au top, pourtant, \u00e7a part plut\u00f4t vite. Je me cale en queue d&rsquo;un groupe de six.<\/span><br class=\"none\" \/><br \/>\n<span style=\"font-size: 14px; color: #000000;\">Nous devons parcourir huit fois une boucle qui forme un triangle d&rsquo;un kilom\u00e8tre entre le canal de l&rsquo;Ourcq et l&rsquo;all\u00e9e du Belv\u00e9d\u00e8re. Les trois premiers filent comme des fus\u00e9es. Je ne peux pas les suivre.<\/span> <span style=\"font-size: 14px; color: #000000;\">Les deux suivants ne sont pas tr\u00e8s loin et je les rejoints avant la fin du premier tour. Ils ont br\u00fbl\u00e9; Ils sont partis trop vite.<\/span> <span style=\"font-size: 14px; color: #000000;\">Je ne suis habituellement pas tr\u00e8s v\u00e9loce mais quand je vois mon mon chrono d\u00e9passer les 4mn alors que je n&rsquo;ai pas encore boucl\u00e9 le premier tour, je m&rsquo;inqui\u00e8te un peu. 4:05 pour un kilom\u00e8tre c&rsquo;est un peu faible. Il m&rsquo;arrive parfois de ressentir comme un frein, l&rsquo;impossibilit\u00e9 de d\u00e9rouler proprement; mais ce n&rsquo;est pas le cas ce matin. Je ne me sens pas particuli\u00e8rement lent. J&rsquo;imagine que la distance annonc\u00e9e est approximative et que le tour peut aussi bien faire 1100m, personne ne s&rsquo;en plaindra.<\/span> <span style=\"font-size: 14px; color: #000000;\">Le circuit forme un triangle. On commence par une longue ligne droite de 455m sur l&rsquo;all\u00e9e du Belv\u00e9d\u00e8re puis on longe le canal de l&rsquo;Ourcq pendant 455m puis on slalom autour du Z\u00e9nith pour revenir sur l&rsquo;all\u00e9e du Belv\u00e9d\u00e8re. C&rsquo;est un peu monotone; moins qu&rsquo;une piste d&rsquo;athl\u00e9tisme mais je fatigue un peu \u00e0 repasser ind\u00e9finiment aux m\u00eames endroits.<\/span> <span style=\"font-size: 14px; color: #000000;\">Cela dit il y a un avantage \u00e0 tourner comme un poisson dans son bocal, on a toujours quelqu&rsquo;un \u00e0 doubler, un courir en point de mire qui \u00e9vite de s&rsquo;endormir.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong>ANNE<\/strong> : je me m\u00eale aux coureurs au milieu du peloton et je n&rsquo;essaie pas, comme David, d&rsquo;\u00eatre la plus proche de la ligne.<\/span> <span style=\"font-size: 14px; color: #000000;\">Le d\u00e9part est donn\u00e9 et je me retrouve la premi\u00e8re des filles. David m&rsquo;avait conseill\u00e9 de suivre et de m&rsquo;accrocher \u00e0 la premi\u00e8re. Pour le coup c&rsquo;est rat\u00e9, je vais m&rsquo;accrocher \u00e0 moi m\u00eame et tenter de doubler quelques gar\u00e7ons.<\/span> <span style=\"font-size: 14px; color: #000000;\">J&rsquo;ai encore oubli\u00e9 de recharger la montre Garmin que David m&rsquo;a offerte pour mon anniversaire et l&rsquo;\u00e9cran est devenu noir avant m\u00eame que la course ne commence. Je ne connais ni mon temps, ni ma vitesse; je cours en aveugle, avec mes seules sensations.<\/span><br class=\"none\" \/><br class=\"none\" \/><br \/>\n<span style=\"font-size: 16px;\"><strong><span style=\"color: #000000;\">&#8211; EPISODE 5 &#8211;<\/span><\/strong><\/span><br class=\"none\" \/><br \/>\n<a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/image41.jpeg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-4008\" style=\"margin-left: 10px; margin-right: 10px;\" alt=\"image[4]\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/image41-199x300.jpeg\" width=\"199\" height=\"300\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/image41-199x300.jpeg 199w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/image41.jpeg 588w\" sizes=\"auto, (max-width: 199px) 100vw, 199px\" \/><\/a><span style=\"font-size: 14px; color: #000000;\"><strong>DAVID<\/strong> : Je double ma s\u0153ur pour la premi\u00e8re fois au milieu du troisi\u00e8me tour. Elle court sereinement en mode finisher. \u00c0 la fin du quatri\u00e8me tour, je remonte au niveau du troisi\u00e8me qui semble en perdition et ne fait pas de mani\u00e8re pour se laisser doubler le long du canal. Je suis troisi\u00e8me; je peux faire un podium si j&rsquo;arrive \u00e0 maintenir mon allure et qu&rsquo;aucun gars ne revienne sur moi.<\/span> <span style=\"font-size: 14px; color: #000000;\">Pourtant, au milieu du cinqui\u00e8me tour, un coureur arrive \u00e0 mon niveau. Je l&rsquo;avais vu s&rsquo;\u00e9chauffer le long de l&rsquo;all\u00e9e avant le d\u00e9part, je pensais qu&rsquo;il faisait parti du bin\u00f4me qui s&rsquo;\u00e9tait envol\u00e9 devant moi.<\/span> <span style=\"font-size: 14px; color: #000000;\">Il m&rsquo;annonce que je suis en t\u00eate car les deux premiers se sont arr\u00eat\u00e9s au quatri\u00e8me kilom\u00e8tre. Je comprends mieux leur d\u00e9part fulgurant.<\/span><br class=\"none\" \/><br \/>\n<span style=\"font-size: 14px; color: #000000;\">Cette nouvelle me trouble quelque peu : Je suis en t\u00eate d&rsquo;une course. Cela ne m&rsquo;\u00e9tait jamais arriv\u00e9 auparavant et, surtout, je n&rsquo;imaginais pas que cela puisse arriver un jour.<\/span> <span style=\"font-size: 14px; color: #000000;\">Je cours sur un nuage. Difficile de d\u00e9crire la joie qui m&rsquo;enveloppe pendant ces minutes. Lorsque je double Anne \u00e0 la fin du cinqui\u00e8me tour, puis une seconde fois Marie-Pierre dans le sixi\u00e8me tour, je leur crie que je suis en t\u00eate. Cela ne semble ne leur faire ni chaud ni froid; chacun est dans sa bulle. Je savoure la mienne. Mon allure n&rsquo;a plus trop d&rsquo;importance d\u00e9sormais : Je g\u00e8re ma place. Je contr\u00f4le celui qui court un ou deux m\u00e8tres derri\u00e8re moi.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong>ANNE<\/strong> : je suis premi\u00e8re chez les filles et je vais sans doute le rester car la seconde est loin derri\u00e8re. Je ne compte plus les gars que je double. Je sens bien qu&rsquo;il y a plus de monde derri\u00e8re que devant moi, ce n&rsquo;est pas franchement habituel pour moi!<\/span> <span style=\"font-size: 14px; color: #000000;\">J&rsquo;ai un bon rythme; je crois bien que je n&rsquo;ai jamais couru aussi vite. David me double. Il fanfaronne, il est premier. Je lui r\u00e9ponds que moi aussi je suis premi\u00e8re f\u00e9minine mais il ne m&rsquo;\u00e9coute pas et continue sa course sans pr\u00eater plus d&rsquo;attention \u00e0 la mienne.<\/span><br class=\"none\" \/><br \/>\n<strong><span style=\"font-size: 14px; color: #000000;\"><br class=\"none\" \/><span style=\"font-size: 16px;\">&#8211; EPISODE 7 &#8211;<\/span><\/span><\/strong><br class=\"none\" \/><br \/>\n<a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/Cross-La-Villette-564.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-3996\" style=\"margin-left: 10px; margin-right: 10px;\" alt=\"Cross La Villette 564\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/Cross-La-Villette-564-300x199.jpg\" width=\"300\" height=\"199\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/Cross-La-Villette-564-300x199.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/Cross-La-Villette-564-1024x680.jpg 1024w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/Cross-La-Villette-564-600x398.jpg 600w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/Cross-La-Villette-564.jpg 1062w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><span style=\"font-size: 14px; color: #000000;\"><strong>DAVID :<\/strong> on atteint le huiti\u00e8me tour. L&rsquo;adr\u00e9naline commence \u00e0 m&rsquo;envahir. Tout va se jouer dans quelques minutes. J&rsquo;ai peur que mon poursuivant acc\u00e9l\u00e8re et me l\u00e2che. Je ne veux pas non plus donner le signal d&rsquo;un sprint pr\u00e9coce, cela pourrait lui donner des id\u00e9es et, qui sait, il est peut-\u00eatre bien meilleur que moi \u00e0 ce jeu l\u00e0. Jamais je n&rsquo;ai couru en ayant \u00e0 me poser de telles questions. J&rsquo;inaugure l&rsquo;habitude de courir derri\u00e8re un chrono, pas devant une place.<\/span> <span style=\"font-size: 14px; color: #000000;\">L&rsquo;arriv\u00e9e approche. Partir \u00e0 500m, ce serait trop risqu\u00e9, 400m, 300m,&#8230; On entre dans la cour du Z\u00e9nith. Je l\u00e2che les chevaux. Je m&rsquo;attends \u00e0 voir le second revenir sur moi comme une fus\u00e9e. 250m. Je tourne sur l&rsquo;all\u00e9e du Belv\u00e9d\u00e8re; l&rsquo;arriv\u00e9e est \u00e0 150m de moi. On ne sait jamais, je ne voudrais pas tout perdre si pr\u00e8s du but. Je me jette dans un sprint. La ligne approche, je suis devant.<\/span><br \/>\n<span style=\"font-size: 14px; color: #000000;\">Je retiens mon souffle. Ce n&rsquo;est pas une technique de course, c&rsquo;est la peur qui me tient. Je franchis la ligne en apn\u00e9e. Je suis en t\u00eate, je suis premier.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong>ANNE :<\/strong> dernier tour, j&rsquo;acc\u00e9l\u00e8re l&rsquo;allure pour essayer de d\u00e9passer les hommes encore \u00e0 ma port\u00e9e. \u00c0 chaque fois c&rsquo;est le m\u00eame cin\u00e9ma : ils acc\u00e9l\u00e8rent quand j&rsquo;arrive \u00e0 leur niveau. Ce n&rsquo;est pas de se faire doubler qui les g\u00eanent; l\u00e0 o\u00f9 il en sont, ils ne courent plus pour le podium. C&rsquo;est d&rsquo;\u00eatre doubl\u00e9 par une femme qui les vexe et c&rsquo;est aussi ce qui me donne le courage de tenir bon et de les l\u00e2cher.<\/span> <span style=\"font-size: 14px; color: #000000;\">Je vois l&rsquo;arriv\u00e9e, j&rsquo;entends des encouragements. D&rsquo;habitude, sur les courses, je passe toujours inaper\u00e7ue; aujourd&rsquo;hui c&rsquo;est une autre histoire : je termine premi\u00e8re. David m&rsquo;accueille et me f\u00e9licite.<\/span><br \/>\n<span style=\"font-size: 14px; color: #000000;\"><br class=\"none\" \/><span style=\"font-size: 16px;\"><strong>&#8211; EPISODE 8 &#8211;<\/strong><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/Cross-La-Villette-647.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-3997\" style=\"margin-left: 10px; margin-right: 10px;\" alt=\"Cross La Villette 647\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/Cross-La-Villette-647-199x300.jpg\" width=\"199\" height=\"300\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/Cross-La-Villette-647-199x300.jpg 199w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/Cross-La-Villette-647.jpg 469w\" sizes=\"auto, (max-width: 199px) 100vw, 199px\" \/><\/a>DAVID :<\/strong> Je goute pendant quelques minutes qui durent au moins un si\u00e8cle au plaisir de la victoire.<\/span> <span style=\"font-size: 14px; color: #000000;\">34&rsquo;20\u00a0\u00bb. C&rsquo;est moyen pour un 8km mais tous ceux qui arrivent derri\u00e8re moi comptent 600 \u00e0 800 m\u00e8tres de plus sur leurs GPS. C&rsquo;est aussi ce que je mesurerai sur une carte IGN, en rentrant chez moi.<\/span> <span style=\"font-size: 14px; color: #000000;\">Anne passe devant moi; elle entame son dernier tour; elle aussi est en t\u00eate, chez les filles.<\/span> <span style=\"font-size: 14px; color: #000000;\">Je remercie Denis, le second. C&rsquo;est lui qui m&rsquo;a inform\u00e9 de ma place et c&rsquo;est l&rsquo;envie de rester devant lui qui m&rsquo;a fait courir pendant trois tours. Nous discutons l&rsquo;un et l&rsquo;autre jusqu&rsquo;\u00e0 ce que Anne Franchisse \u00e0 son tour la ligne d&rsquo;arriv\u00e9e. Je suis assez fier de sa place; au moins autant que de la mienne.<\/span><br class=\"none\" \/><br \/>\n<span style=\"font-size: 14px; color: #000000;\">On nous remet \u00e0 chacun une grande et belle coupe que Th\u00e9ophile s&#8217;empressera d&rsquo;exposer dans sa chambre. J&rsquo;ai couru, comme chaque course cette ann\u00e9e, avec un \u00e9cusson Team-Outdoor brod\u00e9 sous mon \u00e9paule gauche, mais je n&rsquo;ai pas pr\u00e9vu de veste de \u00ab\u00a0podium\u00a0\u00bb. Ce n&rsquo;est pas le genre de truc auquel je suis souvent confront\u00e9 et je suis d\u00e9\u00e7u de ne pas pouvoir rapporter, pour une fois, une photo avec la coupe dans les bras et l&rsquo;\u00e9cusson de la Team au dessus du c\u0153ur.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-size: 14px; color: #000000;\"><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/Cross-La-Villette-781.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-4010\" style=\"margin-left: 10px; margin-right: 10px;\" alt=\"Cross La Villette 781\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/Cross-La-Villette-781-300x199.jpg\" width=\"300\" height=\"199\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/Cross-La-Villette-781-300x199.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/Cross-La-Villette-781-1024x680.jpg 1024w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/Cross-La-Villette-781-600x398.jpg 600w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/Cross-La-Villette-781.jpg 1062w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>ANNE :<\/span><\/strong> <span style=\"font-size: 14px; color: #000000;\">J&rsquo;ai mis 40&rsquo;58\u00a0\u00bb sur un circuit de presque 9km. La deuxi\u00e8me, Carine, arrive en 42:32 et une autre Anne, la suivante,en 46:36. C&rsquo;est la meilleure vitesse \u00e0 laquelle je n&rsquo;ai jamais couru mais ce n&rsquo;\u00e9tait pas trop difficile non plus. Je suis aussi 18eme au scratch; m\u00eame chez les hommes je ne d\u00e9m\u00e9rite pas trop.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\">On nous remet, \u00e0 David et \u00e0 moi, de grosses coupes et quelques cadeaux. C&rsquo;est un peu No\u00ebl avant l&rsquo;heure. Il va falloir g\u00e9rer \u00e7a maintenant. Quand on gagne une fois on imagine qu&rsquo;on peut le refaire; on voudrait le refaire m\u00eame si, malheureusement, toutes les courses ne sont pas aussi faciles \u00e0 gagner. <\/span><\/p>\n<p><span style=\"font-size: 14px; color: #000000;\">L\u00e0 j&rsquo;ai enfin droit de boire un th\u00e9 chaud avec Marie-Pierre, tout aussi th\u00e9 addict que moi. Elle est contente d&rsquo;avoir fait et fini sa 1\u00e8re course, \u00e7a se f\u00eate aussi&#8230; Allez m\u00eame un 2 \u00e8me et un troisi\u00e8me th\u00e9!!<\/span> <span style=\"font-size: 14px; color: #000000;\">C&rsquo;\u00e9tait un moment tr\u00e8s agr\u00e9able, nous sommes rentr\u00e9s \u00e0 la maison en courant, nos coupes dans les bras toujours dans le froid mais l\u00e0 je ne le sentais plus.<\/span><br class=\"none\" \/><br class=\"none\" \/><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/Cross-La-Villette-880.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4001\" alt=\"Cross La Villette 880\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/Cross-La-Villette-880-199x300.jpg\" width=\"199\" height=\"300\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/Cross-La-Villette-880-199x300.jpg 199w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/Cross-La-Villette-880.jpg 469w\" sizes=\"auto, (max-width: 199px) 100vw, 199px\" \/><\/a>\u00a0 <a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/Cross-La-Villette-893.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4002\" alt=\"Cross La Villette 893\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/Cross-La-Villette-893-199x300.jpg\" width=\"199\" height=\"300\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/Cross-La-Villette-893-199x300.jpg 199w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/Cross-La-Villette-893.jpg 469w\" sizes=\"auto, (max-width: 199px) 100vw, 199px\" \/><\/a>\u00a0 <a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/image5.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4009\" alt=\"image[5]\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/image5-199x300.jpeg\" width=\"199\" height=\"300\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/image5-199x300.jpeg 199w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/12\/image5.jpeg 588w\" sizes=\"auto, (max-width: 199px) 100vw, 199px\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><strong><span style=\"font-size: 18px; color: #000000;\">David &amp; Anne<\/span><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dimanche 17 novembre, Paris 19\u00e8me par David MATHIEU et Anne MATHIEU, Team Outdoor Paris -EPISODE 1- DAVID : J&rsquo;aime retourner courir chaque automne le cross d&rsquo;Amnesty International dans le dix-neuvi\u00e8me arrondissement. Il y a plusieurs raisons \u00e0 \u00e7a: D&rsquo;abord c&rsquo;est une course sympathique, sans pr\u00e9tention; une course de village, de quartier, m\u00eame si ce quartier [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4004,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-3998","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-on-l-a-fait","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"_links":{"self":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts\/3998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/comments?post=3998"}],"version-history":[{"count":7,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts\/3998\/revisions"}],"predecessor-version":[{"id":4017,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts\/3998\/revisions\/4017"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/media\/4004"}],"wp:attachment":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/media?parent=3998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/categories?post=3998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/tags?post=3998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}