{"id":4626,"date":"2014-03-20T12:47:19","date_gmt":"2014-03-20T11:47:19","guid":{"rendered":"http:\/\/www.team-outdoor.fr\/blog\/?p=4626"},"modified":"2014-03-20T13:30:42","modified_gmt":"2014-03-20T12:30:42","slug":"le-bonheur-de-retour-sur-les-chemins-par-agnes-herve-au-trail-des-trois-chateaux","status":"publish","type":"post","link":"https:\/\/www.team-outdoor.fr\/blog\/le-bonheur-de-retour-sur-les-chemins-par-agnes-herve-au-trail-des-trois-chateaux\/","title":{"rendered":"Le bonheur de retour sur les chemins.. par Agn\u00e8s HERVE au Trail des Trois Chateaux"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><span style=\"font-size: 18px; color: #000000;\"><br class=\"none\" \/>Dimanche 9 mars 2014, Le Creusot &#8211; Sa\u00f4ne et Loire &#8211; 21.5 kils<br class=\"none\" \/><\/span><\/strong><br class=\"none\" \/><div id='gallery-1' class='gallery galleryid-4626 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.team-outdoor.fr\/blog\/2014-03-09-13-34-56\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/03\/2014-03-09-13.34.56-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.team-outdoor.fr\/blog\/2014-03-09-08-40-11\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/03\/2014-03-09-08.40.11-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.team-outdoor.fr\/blog\/2014-03-09-08-44-33\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/03\/2014-03-09-08.44.33-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.team-outdoor.fr\/blog\/2014-03-09-08-50-02\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/03\/2014-03-09-08.50.02-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.team-outdoor.fr\/blog\/2014-03-09-08-45-54\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/03\/2014-03-09-08.45.54-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.team-outdoor.fr\/blog\/2014-03-09-12-57-40\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/03\/2014-03-09-12.57.40-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.team-outdoor.fr\/blog\/2014-03-09-08-42-31\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/03\/2014-03-09-08.42.31-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.team-outdoor.fr\/blog\/2014-03-09-12-54-57\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/03\/2014-03-09-12.54.57-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong>C\u2019est avec beaucoup d\u2019\u00e9motions et surtout de plaisir<\/strong> que je retrouvais les chemins apr\u00e8s 7 mois\u2026 Et pour ce, j\u2019ai choisi de le faire dans le cadre d\u2019un trail que j\u2019appr\u00e9cie tout particuli\u00e8rement tant par la perfection de l\u2019organisation, le cadre du Ch\u00e2teau du Creusot, le parcours vari\u00e9 et fort sympathique, la flop\u00e9e de marches qui en marquent la fin, l\u2019extr\u00eame gentillesse des b\u00e9n\u00e9voles et des randonneurs crois\u00e9s au fil du chemin\u2026. Sans oublier le soleil qui, comme chaque ann\u00e9e, est au rendez-vous\u2026<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/03\/DSC03923-Copier.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-4622\" style=\"margin-left: 10px; margin-right: 10px;\" alt=\"DSC03923 (Copier)\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/03\/DSC03923-Copier-300x225.jpg\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/03\/DSC03923-Copier-300x225.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/03\/DSC03923-Copier-600x450.jpg 600w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/03\/DSC03923-Copier.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Allez\u2026 petit \u00e9chauffement tranquillou\u2026<\/strong> Petit papotage avec Martine qui fait le combin\u00e9 et pointe \u00e0 la seconde position chez les f\u00e9minines apr\u00e8s une tr\u00e8s belle course nocturne la veille. Les derni\u00e8res recommandations de l\u2019organisateur et c\u2019est d\u00e9j\u00e0 le d\u00e9part.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong>Que dire de la course \u00e0 part que je n\u2019ai pas vu le temps passer\u2026<\/strong> Tout se d\u00e9roule \u00e0 merveille, le d\u00e9part plut\u00f4t tranquille, les relances sur les parties roulantes, les petits chemins qui zigzaguent dans les sous-bois, le plan d\u2019eau qui scintille, les encouragements des b\u00e9n\u00e9voles et des marcheurs\u2026 et d\u00e9j\u00e0 l\u2019arriv\u00e9e avec ses marches qu\u2019il faut gravir en souriant\u2026. Grand sourire \u00e0 l\u2019arriv\u00e9e\u2026 Le bonheur\u00a0! \u2026<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/03\/14-03-09-trail-485-001.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-4625\" style=\"margin-left: 10px; margin-right: 10px;\" alt=\"14-03-09-trail (485)-001\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/03\/14-03-09-trail-485-001-300x231.jpg\" width=\"300\" height=\"231\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/03\/14-03-09-trail-485-001-300x231.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/03\/14-03-09-trail-485-001-1024x790.jpg 1024w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/03\/14-03-09-trail-485-001-600x463.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>S\u2019en suit le buffet repas avant la remise des r\u00e9compenses au sein du Ch\u00e2teau de la Verrerie<\/strong> en compagnie de Martine, Christian, Yann \u2013 qui remporte le combin\u00e9 \u2013 et sa compagne. Un seul regret, avoir \u00e9t\u00e9 oblig\u00e9e de partir avant le Vin d\u2019honneur afin de ne pas rentrer trop tard sur la capitale\u2026. Mais toutes les bonnes choses ont une fin\u2026. Et puis, ce n\u2019est que partie remise, car on remet cela en 2015\u00a0!<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong>Ah si, j\u2019oubliais, une petite anecdote tout de m\u00eame\u2026<\/strong> alors que je l\u00e9zardais au soleil en attendant la remise des r\u00e9compenses, je d\u00e9cide de m\u2019offrir une petite bi\u00e8re pour profiter totalement du moment\u2026 Je me rends donc sous le chapiteau pour demander au gentil monsieur qui s\u2019occupait du fut \u00e0 bi\u00e8re de me servir une tite pression. Le gentil monsieur l\u00e8ve la t\u00eate, me regarde, continue de me regarder\u2026et enfin me lance \u00a0\u00ab\u00a0<em>vous \u00eates s\u00fbre\u00a0?\u00a0<\/em>\u00bb\u2026 \u00ab\u00a0mmmmmm\u00a0? si je suis s\u00fbre\u00a0? \u00ab\u00a0<em>mais vi bien s\u00fbr que je suis s\u00fbre\u00a0!!!<\/em>\u00a0\u00bb et l\u00e0\u00a0 j\u2019ai le droit \u00e0 nouveau \u00ab\u00a0<em>vous \u00eates vraiment s\u00fbre\u00a0?\u00a0<\/em>\u00bb. \u00ab\u00a0<em>mmmmmm\u00a0???<\/em>\u00a0\u00bb Euh, y va finir par me f\u00e2cher le gentil monsieur\u00a0;)\u00a0!!! J\u2019veux ma bi\u00e8re\u00a0!!! j\u2019insiste tandis les personnes derri\u00e8re moi commencent \u00e0 s\u2019impatienter\u2026. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/03\/2.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-4607\" style=\"margin-left: 10px; margin-right: 10px;\" alt=\"2\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/03\/2-300x200.jpg\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/03\/2-300x200.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/03\/2-1024x684.jpg 1024w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/03\/2-600x401.jpg 600w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/03\/2.jpg 1117w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Je ne comprends pas pourquoi le gentil monsieur\u00a0 continue \u00e0 me regarder comme \u00e7a\u2026<\/strong> et \u00e0 nouveau, \u00ab\u00a0<em>vous \u00eates sure que vous avez l\u2019\u00e2ge\u00a0???<\/em> \u00ab\u00a0Euh grand sourire, hihihihihi,je le regarde \u00e9bahie pour voir s\u2019il se moquait de moi\u2026 et \u2026 peut \u00eatre le second effet couettes, ou juste que le gentil monsieur il a but tout le premier fut \u00e0 lui tout seul et que c\u2019est pour cela qu\u2019en plus maintenant qu\u2019il a accept\u00e9 de me servir la bi\u00e8re, on doit attendre de changer de fut\u2026. Ou juste un gentil monsieur charmeur\u00a0;) A bient\u00f4t 37 ans, on ne me l\u2019avait pas faite depuis longtemps celle-l\u00e0\u00a0! Trop boooon\u00a0!&#8230;. Enfin servie, je d\u00e9guste cette tite bi\u00e8re qui a pris encore plus de saveur\u00a0!<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/03\/2014-03-09-13.45.08.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-4621\" style=\"margin-left: 10px; margin-right: 10px;\" alt=\"2014-03-09 13.45.08\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/03\/2014-03-09-13.45.08-225x300.jpg\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/03\/2014-03-09-13.45.08-225x300.jpg 225w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/03\/2014-03-09-13.45.08-768x1024.jpg 768w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/03\/2014-03-09-13.45.08-600x800.jpg 600w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a>Une fois n\u2019est pas coutume, je voulais remercier<\/strong> mon coach, mes clients, mes amis, et le docteur Altervain pour m\u2019avoir soutenue pendant tout ce temps. Le genou est en bonne voie m\u00eame s\u2019il continue \u00e0 me titiller un peu. Merci \u00e0 No\u00ebl pour les photos de ce r\u00e9cit. Et merci \u00e0 toute l\u2019\u00e9quipe de l\u2019organisation et au speaker pour l\u2019accueil et la gentillesse. A l\u2019ann\u00e9e prochaine au 3 Ch\u00e2teaux, sans faute\u00a0!<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong>Et enfin, petit clin d\u2019\u0153il du destin ici encore au Creusot<\/strong> avec un dossard porte bonheur et <span style=\"text-decoration: underline;\"><span style=\"color: #800080;\"><a href=\"http:\/\/www.team-outdoor.fr\/blog\/les-championnats-de-france-de-cross-country-le-pontet-84-par-le-top-3\/\" target=\"_blank\"><span style=\"color: #800080; text-decoration: underline;\">notre chiffre 13<\/span><\/a><\/span><\/span> qui continue \u00e0 m\u2019accompagner \u00e0 chaque sortie\u2026 Eh vi, si je ne me trompe pas, 2+ 5 +6 =\u00a0?\u00a0;)<br class=\"none\" \/><br class=\"none\" \/><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 14px; color: #000000;\"><strong><span style=\"font-size: 18px;\">agn\u00e8s<\/span><\/strong><br class=\"none\" \/><br class=\"none\" \/><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/03\/2014-03-09-13.24.16.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-4617\" alt=\"2014-03-09 13.24.16\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/03\/2014-03-09-13.24.16-1024x768.jpg\" width=\"717\" height=\"538\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/03\/2014-03-09-13.24.16-1024x768.jpg 1024w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/03\/2014-03-09-13.24.16-300x225.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/03\/2014-03-09-13.24.16-600x450.jpg 600w\" sizes=\"auto, (max-width: 717px) 100vw, 717px\" \/><\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dimanche 9 mars 2014, Le Creusot &#8211; Sa\u00f4ne et Loire &#8211; 21.5 kils C\u2019est avec beaucoup d\u2019\u00e9motions et surtout de plaisir que je retrouvais les chemins apr\u00e8s 7 mois\u2026 Et pour ce, j\u2019ai choisi de le faire dans le cadre d\u2019un trail que j\u2019appr\u00e9cie tout particuli\u00e8rement tant par la perfection de l\u2019organisation, le cadre du [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4625,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-4626","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-on-l-a-fait","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"_links":{"self":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts\/4626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/comments?post=4626"}],"version-history":[{"count":8,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts\/4626\/revisions"}],"predecessor-version":[{"id":4629,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts\/4626\/revisions\/4629"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/media\/4625"}],"wp:attachment":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/media?parent=4626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/categories?post=4626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/tags?post=4626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}