{"id":4736,"date":"2014-04-17T09:26:26","date_gmt":"2014-04-17T08:26:26","guid":{"rendered":"http:\/\/www.team-outdoor.fr\/blog\/?p=4736"},"modified":"2014-04-17T09:30:27","modified_gmt":"2014-04-17T08:30:27","slug":"un-rendez-vous-a-ne-pas-manquer-avec-lequipe-de-team-outdoor-la-course-des-carrieres-18-mai-2014","status":"publish","type":"post","link":"https:\/\/www.team-outdoor.fr\/blog\/un-rendez-vous-a-ne-pas-manquer-avec-lequipe-de-team-outdoor-la-course-des-carrieres-18-mai-2014\/","title":{"rendered":"Un rendez-vous \u00e0 ne pas manquer avec l&rsquo;\u00e9quipe de Team Outdoor, la course des Carri\u00e8res, 18 mai 2014"},"content":{"rendered":"<p style=\"text-align: center;\"><span style=\"font-size: 18px;\"><strong><span style=\"color: #000000;\">Course des Carri\u00e8res, 11 kils et 22 kils, Mondeville (91) le 18 mai 2014<br class=\"none\" \/><br class=\"none\" \/><br class=\"none\" \/><div id='gallery-1' class='gallery galleryid-4736 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.team-outdoor.fr\/blog\/un-rendez-vous-a-ne-pas-manquer-avec-lequipe-de-team-outdoor-la-course-des-carrieres-18-mai-2014\/attachment\/2014\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/04\/2014-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.team-outdoor.fr\/blog\/vluu-l100-m100-samsung-l100-m100-14\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/05\/SDC13810-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.team-outdoor.fr\/blog\/la-course-des-carrieres-par-notre-invite-top-david-mathieu\/vluu-l100-m100-samsung-l100-m100-15\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/05\/SDC13822-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.team-outdoor.fr\/blog\/2-12\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/04\/21-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.team-outdoor.fr\/blog\/p1160189\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/05\/P1160189-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.team-outdoor.fr\/blog\/1-14\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/04\/11-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.team-outdoor.fr\/blog\/p1160175\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/05\/P1160175-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.team-outdoor.fr\/blog\/la-veillee-du-bois-seigneur-des-faisceaux\/ts-oranges-etendus-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2013\/09\/TS-oranges-\u00e9tendus1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n<\/p>\n<p><\/span><\/strong><\/span><\/p>\n<div>\n<div>\n<div>\n<div id=\"id_534f8e0c8ad2d7013185648\" style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\">Ne ratez pas la Fameuse <strong>course des CARRI\u00c8RES<\/strong> qui a lieu cette ann\u00e9e le dimanche 18 mai 2014 \u00e0 Mondeville (91). Deux distances au choix (22 kils et 11 kils en une seule boucle) \u00e0 travers les champs, les sous-bois, les roches et les carri\u00e8res de sable. D\u00e9paysement et convivialit\u00e9 garanties pour cette course organis\u00e9e d&rsquo;une main de ma\u00eetre par Jean-Pierre et Martine DELHOTAL.<br class=\"none\" \/><br class=\"none\" \/><\/span><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\">La course des Carri\u00e8res \u00e9tant une de nos courses partenaire pr\u00e9f\u00e9r\u00e9e, sous souhaitons par ailleurs en faire un grand rendez-vous pour les clients de TEAM OUTDOOR. C&rsquo;est pourquoi, nous proposons \u00e0 nos clients de nous y retrouver, en s&rsquo;inscrivant au magasin sous <strong>TEAM OUTDOOR PARIS<\/strong> et en courant avec le nouveau Tee Shirt de TEAM OUTDOOR et en recevant un bon d&rsquo;achat de 15 euros chez TO.<\/span><span style=\"font-size: 14px; color: #000000;\"> <br class=\"none\" \/><br class=\"none\" \/>Pour plus d&rsquo;informations sur la course ou le bulletin d&rsquo;inscription, c&rsquo;est ici : <span style=\"text-decoration: underline;\"><span style=\"color: #800080; text-decoration: underline;\"><a href=\"http:\/\/www.trail91.fr\/les-carrieres-2014-description-inscription\/\" target=\"_blank\"><span style=\"color: #800080; text-decoration: underline;\">http:\/\/www.trail91.fr\/les-carrieres-2014-description-inscription\/<\/span><\/a><\/span><\/span><\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Course des Carri\u00e8res, 11 kils et 22 kils, Mondeville (91) le 18 mai 2014 Ne ratez pas la Fameuse course des CARRI\u00c8RES qui a lieu cette ann\u00e9e le dimanche 18 mai 2014 \u00e0 Mondeville (91). Deux distances au choix (22 kils et 11 kils en une seule boucle) \u00e0 travers les champs, les sous-bois, les [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4732,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-4736","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveau-chez-to","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"_links":{"self":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts\/4736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/comments?post=4736"}],"version-history":[{"count":6,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts\/4736\/revisions"}],"predecessor-version":[{"id":4744,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts\/4736\/revisions\/4744"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/media\/4732"}],"wp:attachment":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/media?parent=4736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/categories?post=4736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/tags?post=4736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}