{"id":5118,"date":"2014-05-21T06:44:20","date_gmt":"2014-05-21T05:44:20","guid":{"rendered":"http:\/\/www.team-outdoor.fr\/blog\/?p=5118"},"modified":"2014-05-21T06:45:53","modified_gmt":"2014-05-21T05:45:53","slug":"les-carrieres-une-course-a-ne-pas-rater-par-benoit-gandelot-team-outdoor-paris","status":"publish","type":"post","link":"https:\/\/www.team-outdoor.fr\/blog\/les-carrieres-une-course-a-ne-pas-rater-par-benoit-gandelot-team-outdoor-paris\/","title":{"rendered":"Les Carri\u00e8res, une course \u00e0 ne pas rater, par Beno\u00eet Gandelot Team Outdoor Paris"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><span style=\"font-size: 18px;\"><br class=\"none\" \/>Dimanche 18 mai 2014, Mondeville (91) sur le 22 kilom\u00e8tres<br class=\"none\" \/><br class=\"none\" \/><br class=\"none\" \/><\/span><\/strong><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/05\/20140518_091116.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-5060\" alt=\"20140518_091116\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/05\/20140518_091116-1024x769.jpg\" width=\"614\" height=\"461\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/05\/20140518_091116-1024x769.jpg 1024w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/05\/20140518_091116-300x225.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/05\/20140518_091116-600x451.jpg 600w\" sizes=\"auto, (max-width: 614px) 100vw, 614px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong><br class=\"none\" \/><br class=\"none\" \/>La course des carri<\/strong><\/span><span style=\"font-size: 14px; color: #000000;\"><strong><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/05\/00025-Copie.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-5050\" style=\"margin-left: 10px; margin-right: 10px;\" alt=\"_00025 - Copie\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/05\/00025-Copie-300x200.jpg\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/05\/00025-Copie-300x200.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/05\/00025-Copie-600x400.jpg 600w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/05\/00025-Copie.jpg 899w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/strong><\/span><span style=\"font-size: 14px; color: #000000;\"><strong>\u00e8res fait partie des comp\u00e9titions que je m&rsquo;autorise \u00e0 ne rater que pour de bonnes raisons.<\/strong> Tout pousse \u00e0 y revenir : l&rsquo;ambiance d\u00e9tendue, la gentillesse des organisateurs, le parcours assez \u00ab\u00a0casse-pattes\u00a0\u00bb et le T<\/span><span style=\"font-size: 14px; color: #000000;\">eam Outdoor qui est partenaire. En plus, c&rsquo;est ici que j&rsquo;ai commenc\u00e9 le trail ! Motivation suppl\u00e9mentaire cette ann\u00e9e, la majeure partie du Team francilien fait le d\u00e9placement et les clients du magasin vont venir courir sous no<\/span><span style=\"font-size: 14px; color: #000000;\">s nouvelles couleurs. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong>Pour ma part, c&rsquo;est mon deuxi\u00e8me trail \u00ab\u00a0test\u00a0\u00bb apr\u00e8s le sanglier il y a dix jours<\/strong> et, si ma fracture de fatigue semble d\u00e9sormais gu\u00e9rie, les sensations ont encore du mal \u00e0 reveni<\/span><span style=\"font-size: 14px; color: #000000;\">r apr\u00e8s une pause de 5 semaines. C&rsquo;est donc plus pour le plaisir que je m&rsquo;aligne ce matin. De toute fa\u00e7on, avec Tom, Tonio, Pierrot et Nico chez les mecs et Agn\u00e8s chez les filles, il me parait clair que le Team sera bien repr\u00e9sent\u00e9 \u00e0 l&rsquo;arriv\u00e9e. Parmi les autres favoris, il y a l&rsquo;inusable <strong>Am\u00e9rico Machado<\/strong>, tr\u00e8s en forme en ce moment, et probablement <strong>Laurent Brochard,<\/strong> en pleine pr\u00e9paration pour la maxi-race du lac d&rsquo;Annecy. Il y a moyen d&rsquo;avoir une belle bagarre.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong>A force de tra\u00eener pendant mon \u00e9chauffement, je suis \u00e0 deux doigts de manquer le d\u00e9part<\/strong> et j&rsquo;ai juste le temps de me placer en premi\u00e8re ligne avant de m&rsquo;\u00e9lancer dans la campagne. Les 3 premiers kilom\u00e8tres sont tra\u00eetres car tr\u00e8s roulants et, bien s\u00fbr, nous partons assez vite (16km\/h). Je me maintiens sans trop de probl\u00e8me dans le groupe de t\u00eate compos\u00e9, aux trois quarts, de coureurs du Team. Tout le monde \u00e0 l&rsquo;air bien, particuli\u00e8rement Tom (malgr\u00e9 son steeple de la veille aux interclubs) et Pierrot qui m&rsquo;ont l&rsquo;air impatients d&rsquo;en d\u00e9coudre dans les c\u00f4tes.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong>A la premi\u00e8re descente je d\u00e9chante tr\u00e8s vite<\/strong> (certes c&rsquo;est un de mes gros points faibles) : le peloton de t\u00eate me met 30 m\u00e8tres. D\u00e8s lors je ne fais que perdre du terrain, en gardant n\u00e9anmoins tout le monde en vue (le jaune \u00e7a se voit de loin) dans les lignes droites. Progressivement, je reviens sur <strong>Thierry Eclache<\/strong>, avec lequel je fais quelques kilom\u00e8tres (il reprend dans les descentes ce que je lui ai pris en mont\u00e9e). <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong>Aux al<\/strong><\/span><span style=\"font-size: 14px; color: #000000;\"><strong><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/05\/00015.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-5051\" style=\"margin-left: 10px; margin-right: 10px;\" alt=\"_00015\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/05\/00015-300x200.jpg\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/05\/00015-300x200.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/05\/00015-600x400.jpg 600w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/05\/00015.jpg 899w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/strong><\/span><span style=\"font-size: 14px; color: #000000;\"><strong>entours du douzi\u00e8me,<\/strong> le peloton de t\u00eate est d\u00e9sormais loin (je ne l\u2019aper\u00e7ois qu&rsquo;\u00e0 l&rsquo;occasion des longs passages dans les champs) et je sens que je commence \u00e0 faiblir. Le manque d&rsquo;entrainement se fait sentir et les c\u00f4tes sont d<\/span><span style=\"font-size: 14px; color: #000000;\">e plus en plus p\u00e9nibles. Thierry me distance de plus en plus, je sais que je ne le reverrais plus. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong>Vers le seizi\u00e8me, j&rsquo;ai la mauvaise surprise de trouver Pierrot<\/strong> sur le bord du chemin, arr\u00eat\u00e9. Il s&rsquo;est fait une entorse \u00e0 la cheville et ne peut plus courir. Vraiment pas de chance car je pense qu&rsquo;il pouvait s\u00e9rieusement viser le podium mais ce qui m&rsquo;inqui\u00e8te surtout c&rsquo;est sa course de dans quinze jours, chez lui au Pays Basque, qu&rsquo;il doit faire avec Mat (excus\u00e9 aujourd&rsquo;hui car grasse matin\u00e9e\u2026\u2026) et pour laquelle il se pr\u00e9pare depuis un petit moment &#8230; <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong><a href=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/05\/111.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-5122\" style=\"margin-left: 10px; margin-right: 10px;\" alt=\"11\" src=\"http:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/05\/111-300x199.jpg\" width=\"300\" height=\"199\" srcset=\"https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/05\/111-300x199.jpg 300w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/05\/111-1024x682.jpg 1024w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/05\/111-600x399.jpg 600w, https:\/\/www.team-outdoor.fr\/blog\/wp-content\/uploads\/2014\/05\/111.jpg 2000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Dix-neuvi\u00e8me kilo, nous traversons la maison de JP Delhotal,<\/strong> maire de Mondeville et organisateur de la course (et de bien d&rsquo;autres sur Mondeville que je vous recommande : Cul d&rsquo;Enfer, Carri\u00e8res By Night, &#8230;). Je sais que derri\u00e8re ce ne sont que des champs jusqu&rsquo;\u00e0 l&rsquo;arriv\u00e9e. Je n&rsquo;ai plus rien \u00e0 perdre ou \u00e0 gagner mais, pour la forme, j&rsquo;acc\u00e9l\u00e8re en essayant de ne pas finir en roue libre. Bon ce n&rsquo;est pas un rythme de TGV (15\/16) mais je fais au mieux. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px; color: #000000;\"><strong>Je passe l&rsquo;arriv\u00e9e apr\u00e8s 1h38 de course \u00e0 la huiti\u00e8me place.<\/strong> 5&rsquo;30 de plus que l&rsquo;an dernier (et 500m de plus \u00e9galement). Globalement je suis plut\u00f4t content, m\u00eame s&rsquo;il reste du boulot, je me sens mieux qu&rsquo;il y a dix jours et je retrouve des sensations. Tom et Agn\u00e8s gagnent tous les deux, Nico est au pied du podium, Tonio est sixi\u00e8me : le Team aura fait bonne figure ;-). <br class=\"none\" \/><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 20px; color: #000000;\"><strong>Ben<\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dimanche 18 mai 2014, Mondeville (91) sur le 22 kilom\u00e8tres La course des carri\u00e8res fait partie des comp\u00e9titions que je m&rsquo;autorise \u00e0 ne rater que pour de bonnes raisons. Tout pousse \u00e0 y revenir : l&rsquo;ambiance d\u00e9tendue, la gentillesse des organisateurs, le parcours assez \u00ab\u00a0casse-pattes\u00a0\u00bb et le Team Outdoor qui est partenaire. En plus, c&rsquo;est [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5072,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-5118","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-on-l-a-fait","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"_links":{"self":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts\/5118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/comments?post=5118"}],"version-history":[{"count":3,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts\/5118\/revisions"}],"predecessor-version":[{"id":5124,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/posts\/5118\/revisions\/5124"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/media\/5072"}],"wp:attachment":[{"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/media?parent=5118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/categories?post=5118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.team-outdoor.fr\/blog\/wp-json\/wp\/v2\/tags?post=5118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}